{"id":6441,"date":"2025-05-21T18:16:56","date_gmt":"2025-05-21T16:16:56","guid":{"rendered":"https:\/\/gothein.de\/reiseblog\/?p=6441"},"modified":"2025-05-22T13:54:23","modified_gmt":"2025-05-22T11:54:23","slug":"von-dillingen-nach-neuburg","status":"publish","type":"post","link":"https:\/\/gothein.de\/reiseblog\/2025\/05\/21\/von-dillingen-nach-neuburg\/","title":{"rendered":"Von Dillingen nach Neuburg"},"content":{"rendered":"\n<p>Das Fr\u00fchst\u00fcck im Sleepy Sleepy Hotel wurde im knallgr\u00fcnen Fr\u00fchst\u00fcckssaal serviert. Es war nicht viel los, was wahrscheinlich am Aufpreis von 14\u20ac pro Person lag. Es\u00a0war nicht \u00fcppig, aber von allem was da und wir waren zufrieden.<\/p>\n\n\n\n<p>Die Wetterprognose war ziemlich schlecht und die Wege, die als Donauradweg ausgezeichnet sind, versprachen wieder Staub, Schmutz und Schlagl\u00f6cher. Angesichts des prognostizierten Starkregens, Gewitters und Hagels habe ich Komoot nach einer Strecke f\u00fcr das Rennrad befragt, der wir dann gefolgt sind. Pfeilgerade geht es \u00fcber vollst\u00e4ndig ausgebaute Radwege entlang der B16 bis nach Donauw\u00f6rth. F\u00fcr uns erfreulich war eine Baustelle ab H\u00f6chst\u00e4dt, so dass wir v\u00f6llig ungest\u00f6rt einige Kilometer auf dem nichtgesperrten super asphaltierten Radweg fahren konnten. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"763\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884-763x1024.jpg\" alt=\"\" class=\"wp-image-6442\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884-763x1024.jpg 763w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884-224x300.jpg 224w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884-768x1030.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884-1145x1536.jpg 1145w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884-1527x2048.jpg 1527w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1434303502079332095844884.jpg 1864w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" \/><\/figure>\n\n\n\n<p>So haben wir die kurzen 25 km bis Donauw\u00f6rth mit einem Schnitt von 21 km\/h schon nach einer guten Stunde erreicht. Da sich erste kleine Tr\u00f6pfchen auf uns niederlie\u00dfen, verzichteten wir auf die Stadtbesichtigung und fuhren s\u00fcdlich um die Stadt herum. Hier wurde die Navigation etwas schwieriger, bis wir den richtigen Weg wieder hatten. Meistens gab es gut ausgebaute Radwege, aber kurze Passagen waren wir auch auf gr\u00f6\u00dferen verkehrsreicheren Stra\u00dfen unterwegs. <\/p>\n\n\n\n<p>Das erste Foto des Tages habe ich dann in Genderkingen gemacht, wo wir auf die &#8222;romantische Stra\u00dfe (vom Main bis an die Alpen)&#8220; eingebogen sind. Kurz danach \u00fcberqueren wir den ziemlich breiten Lech, der kurz danach in die Donau einm\u00fcndet und kommen dann in die &#8222;historische Stadt Rain&#8220;, wie sie sich selbst selbstbewusst bezeichnet. Es gibt ein Stadttor aus Ziegeln und ein Denkmal f\u00fcr den Feldherrn Tilly. Kurz bevor wir in den Ort einfahren, ist die riesige S\u00fcdzucker-Raffinerie zu sehen. Das Tilly-Denkmal erinnert an eine Schlacht in der N\u00e4he am 15. April 1632, in der besagter Feldherr t\u00f6dlich verletzt wurde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-1024x1024.jpg\" alt=\"\" class=\"wp-image-6443\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-1536x1536.jpg 1536w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-2048x2048.jpg 2048w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_16194799236094859439330-60x60.jpg 60w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Kurz nach Rain begann es st\u00e4rker zu regnen, wir begannen schon die Regensachen anzuziehen, aber es h\u00f6rte dann gleich wieder auf, so dass wir Neuburg an der Donau nach knapp vier Stunden trocken erreicht haben und kurz vor 14h unser kleines Hotel Garni am Schrannenplatz beziehen k\u00f6nnen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-1024x1024.jpg\" alt=\"\" class=\"wp-image-6447\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-1536x1536.jpg 1536w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-2048x2048.jpg 2048w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1808101631105776641067348-60x60.jpg 60w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nach einem Besuch in der Konditorei, unserer ersten Pause f\u00fcr heute, wandern wir entlang der Donau, mit einem einsamen Paddler \u00fcber die Elisenbr\u00fccke mit Blick auf die Altstadt und dann durch die Altstadt mit Barock und Rokoko bis zum Obertor. Die Sankt Peter Kirche ist voller Barock, Bilder und Statuen, insbesondere der Dame, die auf einer Schlange steht.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-1024x1024.jpg\" alt=\"\" class=\"wp-image-6444\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-1536x1536.jpg 1536w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-2048x2048.jpg 2048w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2025\/05\/20250521_1622325104501565588008826-60x60.jpg 60w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Abends f\u00fchrt uns die Google Bewertung 4.4 in den Gasthof Rennbahn, alles was besser bewertet ist, scheinen Kebabs zu sein. Oben ist heute eine Versammlung, zu dem alle zwei Jahre stattfindenden Schlossfest und ein Gro\u00dfteil der Neuburger scheint da mitzumachen. Verschiedene Teilnehmer essen noch schnell was. Die Unterhaltungen h\u00f6ren sich schon sehr bayrisch an, w\u00e4hrend in Dillingen noch das Schw\u00e4bische dominierte.<\/p>\n\n\n\n<p>Was uns anf\u00e4nglich noch kurzweilig erscheint, f\u00fchrt zunehmend zu Ver\u00e4rgerung, denn w\u00e4hrend alle aufgetischt bekommen, sind wir nach einer Stunde immer noch ohne Essen. Uneinsichtiges Personal (keiner ist Schuld) und ein recht einfach zurecht gemachter Salatteller schm\u00e4lern das Vergn\u00fcgen deutlich. W\u00e4hrend wir essen kommt der lang angek\u00fcndigte Regen, der sich aber wieder verzogen hatte, als wir fertig waren.<\/p>\n\n\n\n<p>Danach werden wir mit einem ziemlich eindr\u00fccklichen Konzert entsch\u00e4digt. Zuvor hatte ich ein bisschen recherchiert und habe gesehen, dass das &#8222;American-Roots-Duo True North mit Kristen Grainger und Dan Wetzel)&#8220; in der Klavierschule Pi\u00f9 Piano auftreten. Einfache melodi\u00f6se Lieder , 1-2 Gitarren und sch\u00f6ne Stimmen war ein H\u00f6hepunkt. James ist der Leiter der Klavierschule, der sich um solche Konzerte bem\u00fcht, ist Kanadier und in Neuburg h\u00e4ngen geblieben. Er meint, dass es ein Geschenk w\u00e4re, dass die beiden uns beehren, da sie sonst vor viel gr\u00f6\u00dferem Publikum spielen, statt vor den knapp 40 Leuten, die in der Klavierschule Platz gefunden hatten.<\/p>\n\n\n\n<p>Durch die Abk\u00fcrzungen \u00fcber die gut ausgebauten Radwege sind wir heute 63 km mit 337 H\u00f6henmetern bei bedecktem Himmel und ganz wenigen Regentropfen unterwegs gewesen. Die H\u00f6henmeter sammelten sich haupts\u00e4chlich im letzten Teil der Tour, wo die Landschaft wieder deutlich h\u00fcgeliger wurde. <\/p>\n\n\n\r\n\t\t<div id=\"wpgpxmaps_6441_4242604\" class=\"wpgpxmaps\">\r\n\t\t\t<div id=\"map_6441_4242604_cont\" style=\"width:100%; height:450px;position:relative\" >\r\n\t\t\t\t<div id=\"map_6441_4242604\" style=\"width:100%; height:450px\"><\/div>\r\n\t\t\t\t<div id=\"wpgpxmaps_6441_4242604_osm_footer\" class=\"wpgpxmaps_osm_footer\" style=\"display:none;\"><span> &copy; <a href=\"http:\/\/www.openstreetmap.org\/copyright\">OpenStreetMap<\/a> contributors<\/span><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<canvas id=\"myChart_6441_4242604\" class=\"plot\" style=\"width:100%; height:200px\"><\/canvas>\r\n\t\t\t<div id=\"ngimages_6441_4242604\" class=\"ngimages\" style=\"display:none\"><\/div>\r\n\t\t\t<div id=\"report_6441_4242604\" class=\"report\"><\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<script type=\"text\/javascript\">\r\n\r\n\t\t\tjQuery(document).ready(function() {\r\n\r\n\t\t\t\tjQuery( \"#wpgpxmaps_6441_4242604\" ).wpgpxmaps( {\r\n\t\t\t\t\ttargetId           : \"6441_4242604\",\r\n\t\t\t\t\tmapType            : \"HYBRID\",\r\n\t\t\t\t\tmapData            : [[48.5783496,10.4957733],[48.5784439,10.4957327],[48.5787223,10.4957358],[48.5789318,10.4956679],[48.5790956,10.4955514],[48.5791837,10.4955203],[48.5794227,10.4955236],[48.5795365,10.4955006],[48.5796644,10.4954866],[48.5799238,10.4954880],[48.5801919,10.4954227],[48.5804528,10.4953385],[48.5807013,10.4952782],[48.5808696,10.4952454],[48.5809886,10.4952002],[48.5811257,10.4951764],[48.5812754,10.4954467],[48.5813403,10.4955603],[48.5814527,10.4958176],[48.5815963,10.4963241],[48.5817349,10.4968826],[48.5817715,10.4971179],[48.5818388,10.4974177],[48.5819290,10.4978063],[48.5820220,10.4981957],[48.5821870,10.4989226],[48.5822984,10.4993941],[48.5823364,10.4995391],[48.5824453,10.5000510],[48.5824645,10.5001876],[48.5824775,10.5003658],[48.5825233,10.5005510],[48.5826122,10.5009438],[48.5826491,10.5010875],[48.5826755,10.5012344],[48.5827215,10.5014541],[48.5827698,10.5016676],[48.5829408,10.5024003],[48.5830854,10.5030025],[48.5832426,10.5035264],[48.5834353,10.5041048],[48.5836826,10.5047657],[48.5838719,10.5052144],[48.5840249,10.5056183],[48.5841964,10.5060725],[48.5841795,10.5062130],[48.5841269,10.5063459],[48.5841116,10.5064860],[48.5841466,10.5066234],[48.5842546,10.5068234],[48.5843645,10.5070072],[48.5844652,10.5072140],[48.5846658,10.5076737],[48.5848479,10.5080838],[48.5850733,10.5086632],[48.5852490,10.5090745],[48.5853047,10.5092205],[48.5855286,10.5097286],[48.5857111,10.5101549],[48.5857957,10.5103782],[48.5859060,10.5106745],[48.5860249,10.5109732],[48.5861636,10.5113392],[48.5863890,10.5119535],[48.5865963,10.5124910],[48.5867466,10.5128840],[48.5868304,10.5131031],[48.5870127,10.5136136],[48.5872293,10.5142280],[48.5873418,10.5147384],[48.5873604,10.5150011],[48.5874052,10.5152406],[48.5874865,10.5153492],[48.5876119,10.5154562],[48.5877059,10.5154878],[48.5877866,10.5155654],[48.5878563,10.5156930],[48.5879092,10.5158439],[48.5880945,10.5163947],[48.5883891,10.5171472],[48.5886456,10.5178426],[48.5888954,10.5186305],[48.5889673,10.5188833],[48.5890495,10.5191167],[48.5891516,10.5193308],[48.5892397,10.5195640],[48.5894431,10.5201077],[48.5896561,10.5207304],[48.5899021,10.5214332],[48.5901110,10.5220657],[48.5903408,10.5226961],[48.5905464,10.5232711],[48.5906034,10.5234355],[48.5908348,10.5240925],[48.5908910,10.5242527],[48.5909775,10.5244936],[48.5911775,10.5250536],[48.5914419,10.5257671],[48.5914959,10.5259176],[48.5916589,10.5263801],[48.5918591,10.5269481],[48.5919817,10.5272731],[48.5921230,10.5276738],[48.5921753,10.5278325],[48.5924375,10.5286418],[48.5926909,10.5293858],[48.5928914,10.5300606],[48.5930049,10.5305527],[48.5931460,10.5309875],[48.5932889,10.5314645],[48.5934021,10.5317821],[48.5935109,10.5319717],[48.5936780,10.5323506],[48.5938622,10.5328612],[48.5940825,10.5334484],[48.5942423,10.5339193],[48.5942944,10.5340808],[48.5944679,10.5346284],[48.5946042,10.5350401],[48.5947463,10.5354876],[48.5948482,10.5358484],[48.5949218,10.5360997],[48.5951191,10.5367446],[48.5951574,10.5368749],[48.5952677,10.5372694],[48.5953382,10.5375283],[48.5953748,10.5376551],[48.5955606,10.5382317],[48.5958152,10.5388980],[48.5959033,10.5390405],[48.5960149,10.5392422],[48.5961771,10.5394560],[48.5963312,10.5396470],[48.5965093,10.5398756],[48.5965902,10.5399454],[48.5967257,10.5400926],[48.5968248,10.5402033],[48.5969697,10.5403640],[48.5970797,10.5404746],[48.5971921,10.5405904],[48.5974030,10.5408449],[48.5974728,10.5409312],[48.5977436,10.5412294],[48.5980551,10.5415833],[48.5982434,10.5418143],[48.5983165,10.5419065],[48.5985854,10.5422225],[48.5986565,10.5423214],[48.5989662,10.5426842],[48.5993513,10.5431512],[48.5997081,10.5435491],[48.5997864,10.5436415],[48.6002397,10.5441587],[48.6004013,10.5443644],[48.6004700,10.5445012],[48.6007200,10.5448364],[48.6008064,10.5449378],[48.6009207,10.5450918],[48.6012621,10.5454814],[48.6016574,10.5459290],[48.6020464,10.5464016],[48.6021344,10.5466346],[48.6021539,10.5469370],[48.6022003,10.5471345],[48.6022868,10.5473080],[48.6025051,10.5476055],[48.6026384,10.5477060],[48.6027650,10.5477280],[48.6028669,10.5477462],[48.6029607,10.5477875],[48.6030353,10.5478725],[48.6030931,10.5479794],[48.6032307,10.5481869],[48.6033284,10.5483689],[48.6035010,10.5488040],[48.6037276,10.5493204],[48.6040444,10.5500724],[48.6043396,10.5507362],[48.6046454,10.5514840],[48.6049866,10.5522962],[48.6053296,10.5530883],[48.6056449,10.5538061],[48.6059527,10.5545327],[48.6060465,10.5547535],[48.6063042,10.5553663],[48.6066044,10.5560353],[48.6067310,10.5563285],[48.6068718,10.5566480],[48.6069682,10.5568385],[48.6070587,10.5570265],[48.6071810,10.5572412],[48.6072851,10.5574298],[48.6074344,10.5577629],[48.6074905,10.5578783],[48.6075728,10.5579147],[48.6076654,10.5578978],[48.6077492,10.5581138],[48.6078809,10.5584159],[48.6079314,10.5585347],[48.6080145,10.5587765],[48.6080456,10.5589622],[48.6081470,10.5592677],[48.6082886,10.5596131],[48.6083547,10.5598257],[48.6084575,10.5600975],[48.6085539,10.5604083],[48.6085702,10.5607507],[48.6087402,10.5611503],[48.6089748,10.5616715],[48.6092249,10.5621221],[48.6094990,10.5626211],[48.6096222,10.5629197],[48.6096782,10.5631558],[48.6097337,10.5635302],[48.6097997,10.5640345],[48.6098434,10.5642854],[48.6099296,10.5645117],[48.6100594,10.5646881],[48.6103407,10.5649738],[48.6104799,10.5651310],[48.6105915,10.5653185],[48.6107724,10.5657084],[48.6109035,10.5661064],[48.6110948,10.5669132],[48.6111463,10.5670992],[48.6112247,10.5672486],[48.6113797,10.5673696],[48.6114826,10.5673920],[48.6116619,10.5673840],[48.6117895,10.5673573],[48.6121563,10.5672177],[48.6123425,10.5671368],[48.6124752,10.5670931],[48.6126582,10.5670647],[48.6130236,10.5671521],[48.6133339,10.5671746],[48.6134562,10.5671807],[48.6138301,10.5671594],[48.6139584,10.5671402],[48.6143926,10.5670790],[48.6147664,10.5670492],[48.6153040,10.5669755],[48.6154715,10.5669341],[48.6156921,10.5669915],[48.6159986,10.5672740],[48.6161141,10.5673592],[48.6162300,10.5674107],[48.6166936,10.5675073],[48.6168134,10.5675344],[48.6170439,10.5675908],[48.6172756,10.5676078],[48.6175458,10.5675674],[48.6178214,10.5674900],[48.6179358,10.5674871],[48.6180495,10.5674872],[48.6182694,10.5675550],[48.6183889,10.5676779],[48.6185109,10.5678932],[48.6185730,10.5679945],[48.6188446,10.5685228],[48.6189414,10.5687042],[48.6191073,10.5690056],[48.6193415,10.5695127],[48.6195647,10.5699935],[48.6197769,10.5704802],[48.6198784,10.5706850],[48.6199536,10.5708481],[48.6200675,10.5711249],[48.6201799,10.5713321],[48.6203604,10.5717103],[48.6205491,10.5720520],[48.6207378,10.5723528],[48.6210027,10.5728438],[48.6212094,10.5731472],[48.6213693,10.5734242],[48.6215005,10.5736661],[48.6215948,10.5739542],[48.6216534,10.5740651],[48.6217205,10.5741897],[48.6218093,10.5743507],[48.6218708,10.5744665],[48.6222078,10.5751612],[48.6224072,10.5755477],[48.6225467,10.5758329],[48.6227539,10.5762402],[48.6228122,10.5763677],[48.6230913,10.5769100],[48.6231644,10.5770382],[48.6232280,10.5771484],[48.6233290,10.5773362],[48.6233965,10.5774752],[48.6234773,10.5775974],[48.6235902,10.5778634],[48.6237795,10.5782394],[48.6238489,10.5783575],[48.6239566,10.5785595],[48.6241032,10.5788437],[48.6244087,10.5794173],[48.6246400,10.5798663],[48.6247158,10.5800181],[48.6247938,10.5801639],[48.6249602,10.5804499],[48.6251103,10.5807344],[48.6253041,10.5811107],[48.6256472,10.5817742],[48.6259966,10.5824648],[48.6263513,10.5831451],[48.6264266,10.5833010],[48.6267731,10.5839884],[48.6268574,10.5841452],[48.6270269,10.5844553],[48.6272750,10.5849115],[48.6273502,10.5850600],[48.6274912,10.5853524],[48.6275912,10.5855494],[48.6276899,10.5857283],[48.6277537,10.5858625],[48.6280040,10.5862851],[48.6282991,10.5868279],[48.6286838,10.5875102],[48.6289534,10.5880010],[48.6292533,10.5885851],[48.6295895,10.5892313],[48.6299357,10.5898569],[48.6302129,10.5903844],[48.6304000,10.5907591],[48.6305911,10.5911215],[48.6308481,10.5916376],[48.6311024,10.5921314],[48.6312565,10.5923297],[48.6313264,10.5924204],[48.6314435,10.5926339],[48.6316348,10.5930468],[48.6316800,10.5932061],[48.6317358,10.5933672],[48.6318122,10.5935184],[48.6318973,10.5936594],[48.6321806,10.5942181],[48.6324518,10.5947634],[48.6325877,10.5950129],[48.6327540,10.5953592],[48.6329278,10.5957061],[48.6332596,10.5963600],[48.6335554,10.5969910],[48.6337891,10.5974889],[48.6339173,10.5977442],[48.6341361,10.5981549],[48.6342216,10.5983257],[48.6345509,10.5989010],[48.6346393,10.5990594],[48.6347767,10.5992633],[48.6350591,10.5996569],[48.6352267,10.5998880],[48.6353734,10.6001030],[48.6354714,10.6002314],[48.6356568,10.6005347],[48.6358190,10.6008159],[48.6359514,10.6010471],[48.6360532,10.6012189],[48.6362848,10.6016442],[48.6364500,10.6019611],[48.6365478,10.6021563],[48.6367511,10.6025402],[48.6368582,10.6027308],[48.6369569,10.6029376],[48.6372046,10.6034244],[48.6373249,10.6037034],[48.6374074,10.6038644],[48.6374034,10.6038750],[48.6374487,10.6038765],[48.6375239,10.6040030],[48.6376293,10.6042435],[48.6377261,10.6044832],[48.6378272,10.6046993],[48.6379185,10.6048717],[48.6380074,10.6051545],[48.6381411,10.6054765],[48.6383341,10.6059219],[48.6384344,10.6061688],[48.6386150,10.6066054],[48.6387581,10.6069888],[48.6388407,10.6072018],[48.6389055,10.6073791],[48.6389829,10.6075736],[48.6392053,10.6081346],[48.6394240,10.6086678],[48.6395346,10.6089342],[48.6396752,10.6092960],[48.6397441,10.6094773],[48.6398105,10.6096570],[48.6400396,10.6102929],[48.6401408,10.6105693],[48.6402449,10.6108432],[48.6405504,10.6116818],[48.6406190,10.6118662],[48.6407495,10.6122347],[48.6408923,10.6125744],[48.6410188,10.6128827],[48.6412124,10.6132984],[48.6412998,10.6135261],[48.6413650,10.6136874],[48.6414247,10.6138543],[48.6416847,10.6144625],[48.6417446,10.6146099],[48.6419083,10.6150457],[48.6419628,10.6151959],[48.6421155,10.6152966],[48.6422766,10.6153174],[48.6423963,10.6153365],[48.6424991,10.6155411],[48.6426701,10.6159496],[48.6428214,10.6163050],[48.6428687,10.6164350],[48.6430821,10.6169023],[48.6433684,10.6175644],[48.6434871,10.6178291],[48.6436515,10.6181550],[48.6439024,10.6185215],[48.6439000,10.6186407],[48.6437978,10.6188548],[48.6436699,10.6189616],[48.6436895,10.6191081],[48.6438300,10.6192255],[48.6439525,10.6195174],[48.6441264,10.6199000],[48.6442386,10.6201466],[48.6444260,10.6205798],[48.6447124,10.6211921],[48.6450462,10.6218994],[48.6452708,10.6223767],[48.6453439,10.6225036],[48.6454262,10.6226976],[48.6456038,10.6230673],[48.6459296,10.6237840],[48.6461701,10.6243348],[48.6462411,10.6244862],[48.6464201,10.6248782],[48.6465699,10.6251962],[48.6467341,10.6255682],[48.6468619,10.6258495],[48.6470874,10.6264242],[48.6471511,10.6265627],[48.6474068,10.6270986],[48.6475915,10.6274832],[48.6478737,10.6281279],[48.6481585,10.6287890],[48.6483917,10.6293426],[48.6486989,10.6300288],[48.6490559,10.6308250],[48.6493284,10.6314849],[48.6496338,10.6320978],[48.6499585,10.6327852],[48.6500276,10.6329314],[48.6503348,10.6335969],[48.6506417,10.6342782],[48.6509532,10.6349896],[48.6512916,10.6357536],[48.6515834,10.6363928],[48.6519040,10.6371452],[48.6520163,10.6374007],[48.6522551,10.6379984],[48.6525399,10.6387013],[48.6526048,10.6389396],[48.6526820,10.6391211],[48.6527883,10.6393955],[48.6529120,10.6397408],[48.6531888,10.6403455],[48.6532573,10.6404819],[48.6534166,10.6407360],[48.6537520,10.6412541],[48.6540470,10.6417512],[48.6544096,10.6423880],[48.6545445,10.6426538],[48.6547273,10.6430589],[48.6548149,10.6432629],[48.6549738,10.6436881],[48.6550881,10.6440669],[48.6552275,10.6444177],[48.6553485,10.6447011],[48.6556586,10.6454332],[48.6559313,10.6460164],[48.6561789,10.6466042],[48.6564147,10.6471505],[48.6566443,10.6476907],[48.6568598,10.6481582],[48.6571309,10.6487776],[48.6572393,10.6490465],[48.6573393,10.6492632],[48.6574837,10.6496053],[48.6575645,10.6498273],[48.6578749,10.6505312],[48.6581286,10.6510849],[48.6582811,10.6514399],[48.6584515,10.6518596],[48.6585950,10.6522050],[48.6587233,10.6524704],[48.6589467,10.6530038],[48.6591534,10.6534361],[48.6594766,10.6540596],[48.6597419,10.6545164],[48.6601137,10.6550969],[48.6602942,10.6553391],[48.6603856,10.6554576],[48.6608342,10.6560318],[48.6612712,10.6566245],[48.6613606,10.6567456],[48.6617566,10.6573179],[48.6621419,10.6579147],[48.6622596,10.6581149],[48.6624741,10.6585344],[48.6626699,10.6589928],[48.6627349,10.6591425],[48.6627905,10.6592922],[48.6629460,10.6596636],[48.6632593,10.6604184],[48.6635503,10.6611221],[48.6637953,10.6617337],[48.6639554,10.6621136],[48.6640081,10.6622603],[48.6641249,10.6625758],[48.6642763,10.6629705],[48.6643602,10.6632364],[48.6644277,10.6635129],[48.6644761,10.6636987],[48.6645367,10.6639693],[48.6647200,10.6646942],[48.6649266,10.6655135],[48.6651369,10.6662958],[48.6651903,10.6664934],[48.6653954,10.6672989],[48.6654554,10.6674962],[48.6656400,10.6681905],[48.6657907,10.6687776],[48.6658445,10.6689699],[48.6659404,10.6693670],[48.6661276,10.6702155],[48.6662167,10.6706677],[48.6663040,10.6711205],[48.6663467,10.6713567],[48.6664376,10.6719502],[48.6665105,10.6722984],[48.6665734,10.6725958],[48.6666618,10.6729361],[48.6668439,10.6734868],[48.6669201,10.6736762],[48.6670786,10.6740353],[48.6670916,10.6742085],[48.6671292,10.6743987],[48.6671746,10.6742043],[48.6672479,10.6740605],[48.6673680,10.6739882],[48.6675663,10.6741822],[48.6677400,10.6743270],[48.6678690,10.6744177],[48.6679781,10.6745171],[48.6680490,10.6746125],[48.6681808,10.6747522],[48.6683175,10.6749113],[48.6684363,10.6750497],[48.6685439,10.6751866],[48.6686675,10.6753334],[48.6688296,10.6755083],[48.6690220,10.6757514],[48.6690773,10.6758919],[48.6690684,10.6760304],[48.6691513,10.6762052],[48.6693920,10.6764755],[48.6696914,10.6768622],[48.6700109,10.6773173],[48.6703734,10.6778707],[48.6705199,10.6781069],[48.6707120,10.6784024],[48.6711043,10.6790446],[48.6711852,10.6791864],[48.6714959,10.6796046],[48.6718335,10.6800491],[48.6721475,10.6804611],[48.6724047,10.6808890],[48.6727968,10.6815547],[48.6731284,10.6819856],[48.6734510,10.6825451],[48.6738078,10.6831908],[48.6740884,10.6837133],[48.6742784,10.6840433],[48.6745535,10.6845192],[48.6748530,10.6849884],[48.6750025,10.6852152],[48.6752188,10.6855393],[48.6755144,10.6860189],[48.6758611,10.6866714],[48.6761543,10.6874169],[48.6763766,10.6880993],[48.6765957,10.6888179],[48.6767938,10.6896115],[48.6768278,10.6897787],[48.6768406,10.6900481],[48.6768690,10.6902447],[48.6769281,10.6905500],[48.6770841,10.6913650],[48.6772577,10.6922610],[48.6773766,10.6928423],[48.6775108,10.6934555],[48.6775332,10.6936423],[48.6775665,10.6939033],[48.6776826,10.6944216],[48.6777852,10.6947845],[48.6778661,10.6950945],[48.6779518,10.6954043],[48.6779946,10.6955727],[48.6780688,10.6957907],[48.6782576,10.6963285],[48.6784959,10.6969146],[48.6786764,10.6973955],[48.6787745,10.6976814],[48.6789750,10.6981807],[48.6791618,10.6986450],[48.6793667,10.6991175],[48.6795766,10.6995328],[48.6798049,10.7000043],[48.6801419,10.7007279],[48.6802296,10.7009755],[48.6803151,10.7012323],[48.6803639,10.7014005],[48.6805166,10.7018446],[48.6806269,10.7022373],[48.6807506,10.7026274],[48.6808128,10.7027884],[48.6808794,10.7030731],[48.6809362,10.7032953],[48.6809793,10.7034823],[48.6810542,10.7037987],[48.6810977,10.7040172],[48.6811243,10.7041507],[48.6811751,10.7044612],[48.6813197,10.7052820],[48.6813935,10.7057431],[48.6814903,10.7062882],[48.6816780,10.7069585],[48.6819127,10.7076303],[48.6822680,10.7084158],[48.6823711,10.7085825],[48.6824801,10.7088139],[48.6827297,10.7092372],[48.6828011,10.7093787],[48.6828747,10.7094892],[48.6829737,10.7096495],[48.6831783,10.7099703],[48.6834841,10.7104609],[48.6836555,10.7107385],[48.6837910,10.7109531],[48.6839195,10.7111760],[48.6840488,10.7114358],[48.6841531,10.7116748],[48.6842801,10.7119974],[48.6844368,10.7124216],[48.6846105,10.7128776],[48.6847426,10.7132117],[48.6847928,10.7133366],[48.6848466,10.7135690],[48.6849633,10.7138918],[48.6850272,10.7140562],[48.6850907,10.7142137],[48.6851471,10.7143708],[48.6852150,10.7145381],[48.6852818,10.7147355],[48.6853853,10.7150238],[48.6854669,10.7152425],[48.6855390,10.7154540],[48.6856552,10.7157355],[48.6857109,10.7158999],[48.6857772,10.7160889],[48.6858590,10.7162866],[48.6859849,10.7165978],[48.6861464,10.7169990],[48.6862776,10.7173479],[48.6864261,10.7178170],[48.6864769,10.7180307],[48.6864573,10.7182157],[48.6863940,10.7183583],[48.6863678,10.7185174],[48.6864281,10.7186801],[48.6865546,10.7189349],[48.6868284,10.7194931],[48.6869501,10.7197538],[48.6871069,10.7201136],[48.6872962,10.7205549],[48.6874356,10.7209261],[48.6875388,10.7212093],[48.6876934,10.7218809],[48.6877802,10.7222819],[48.6879169,10.7228635],[48.6881184,10.7237193],[48.6883241,10.7246127],[48.6885211,10.7254710],[48.6886966,10.7263114],[48.6888812,10.7272805],[48.6890095,10.7278541],[48.6891071,10.7279732],[48.6892399,10.7280065],[48.6895990,10.7279483],[48.6897619,10.7279088],[48.6899299,10.7277208],[48.6900361,10.7276595],[48.6901261,10.7277748],[48.6903041,10.7281321],[48.6905588,10.7285976],[48.6907435,10.7289433],[48.6908685,10.7291391],[48.6911163,10.7296026],[48.6912734,10.7298667],[48.6914479,10.7301171],[48.6916126,10.7303761],[48.6917436,10.7305742],[48.6918284,10.7307060],[48.6920734,10.7311078],[48.6921962,10.7313201],[48.6923156,10.7315228],[48.6925461,10.7319231],[48.6926306,10.7320561],[48.6930360,10.7326957],[48.6933898,10.7332755],[48.6937952,10.7339276],[48.6941015,10.7344587],[48.6944375,10.7349880],[48.6947377,10.7354906],[48.6951028,10.7361307],[48.6952754,10.7364368],[48.6954395,10.7367440],[48.6958039,10.7374081],[48.6961652,10.7380426],[48.6964506,10.7385293],[48.6965356,10.7386698],[48.6969234,10.7392669],[48.6970080,10.7393924],[48.6972529,10.7397558],[48.6976292,10.7403512],[48.6978850,10.7407341],[48.6982675,10.7413405],[48.6987009,10.7420102],[48.6990510,10.7425395],[48.6994729,10.7431870],[48.6998968,10.7437972],[48.7002030,10.7443583],[48.7005139,10.7448932],[48.7008430,10.7454989],[48.7011790,10.7460705],[48.7015411,10.7466800],[48.7019540,10.7473636],[48.7020300,10.7474896],[48.7024142,10.7480100],[48.7027881,10.7485285],[48.7030354,10.7488766],[48.7031293,10.7489897],[48.7033595,10.7492892],[48.7034754,10.7494818],[48.7037093,10.7497612],[48.7040023,10.7501122],[48.7040917,10.7502113],[48.7042582,10.7504332],[48.7046755,10.7509227],[48.7049444,10.7512389],[48.7054024,10.7517642],[48.7058668,10.7522854],[48.7063163,10.7528277],[48.7066937,10.7532932],[48.7071933,10.7538726],[48.7074925,10.7542224],[48.7077422,10.7545055],[48.7079809,10.7547858],[48.7081183,10.7549617],[48.7085322,10.7554649],[48.7087686,10.7558891],[48.7089031,10.7562139],[48.7091506,10.7569154],[48.7092103,10.7570513],[48.7092925,10.7571689],[48.7093905,10.7572544],[48.7094820,10.7572945],[48.7095837,10.7573131],[48.7096779,10.7573385],[48.7099318,10.7574315],[48.7099870,10.7576855],[48.7100173,10.7579684],[48.7100394,10.7581041],[48.7099783,10.7582586],[48.7098998,10.7583478],[48.7097804,10.7584908],[48.7096860,10.7585782],[48.7096063,10.7586660],[48.7094869,10.7588832],[48.7094379,10.7590485],[48.7094387,10.7591882],[48.7094391,10.7594491],[48.7094192,10.7597962],[48.7093879,10.7601617],[48.7093376,10.7605846],[48.7093023,10.7607662],[48.7092422,10.7609966],[48.7091891,10.7611751],[48.7091372,10.7613568],[48.7090360,10.7616634],[48.7088570,10.7623085],[48.7088156,10.7624322],[48.7087060,10.7627632],[48.7085216,10.7633331],[48.7083937,10.7637509],[48.7082549,10.7641794],[48.7080199,10.7649138],[48.7078161,10.7655055],[48.7075627,10.7661488],[48.7074993,10.7662856],[48.7072860,10.7667743],[48.7070315,10.7673024],[48.7067072,10.7679306],[48.7065556,10.7682188],[48.7064362,10.7684582],[48.7063052,10.7686869],[48.7061762,10.7689278],[48.7059925,10.7692859],[48.7058530,10.7695087],[48.7057229,10.7696580],[48.7054481,10.7699669],[48.7052796,10.7702538],[48.7052145,10.7703929],[48.7051297,10.7706197],[48.7050766,10.7708426],[48.7050600,10.7709765],[48.7050322,10.7712673],[48.7049621,10.7715740],[48.7049121,10.7717114],[48.7048610,10.7718834],[48.7047476,10.7722757],[48.7046237,10.7727622],[48.7044550,10.7736174],[48.7043685,10.7742248],[48.7042986,10.7748855],[48.7042588,10.7755943],[48.7042511,10.7762947],[48.7042367,10.7769303],[48.7042540,10.7776270],[48.7042614,10.7779331],[48.7042762,10.7785419],[48.7042902,10.7791484],[48.7042519,10.7793889],[48.7041796,10.7794677],[48.7040518,10.7795452],[48.7036997,10.7798224],[48.7034334,10.7800871],[48.7030420,10.7804913],[48.7029519,10.7805769],[48.7027854,10.7807495],[48.7025346,10.7810108],[48.7022491,10.7812246],[48.7021653,10.7812837],[48.7020289,10.7813184],[48.7018612,10.7813442],[48.7017270,10.7815017],[48.7016538,10.7816276],[48.7016856,10.7818320],[48.7018044,10.7818487],[48.7020337,10.7819257],[48.7022214,10.7820604],[48.7023953,10.7822464],[48.7026662,10.7827304],[48.7027892,10.7830495],[48.7028708,10.7831351],[48.7029288,10.7833425],[48.7030221,10.7835741],[48.7032082,10.7839506],[48.7034848,10.7843824],[48.7035985,10.7844910],[48.7037225,10.7847076],[48.7037311,10.7850813],[48.7037008,10.7852905],[48.7035435,10.7855189],[48.7034329,10.7855636],[48.7033495,10.7856700],[48.7030610,10.7860772],[48.7029827,10.7861823],[48.7028986,10.7863096],[48.7025751,10.7867652],[48.7021595,10.7873728],[48.7020182,10.7875920],[48.7019782,10.7877313],[48.7019794,10.7879723],[48.7019840,10.7881361],[48.7020047,10.7887093],[48.7020283,10.7891429],[48.7020670,10.7894046],[48.7022184,10.7901620],[48.7023888,10.7909976],[48.7024250,10.7911611],[48.7025785,10.7918713],[48.7026111,10.7920224],[48.7026758,10.7922813],[48.7027206,10.7924165],[48.7026778,10.7925659],[48.7025922,10.7926327],[48.7022782,10.7928511],[48.7019549,10.7930884],[48.7015125,10.7934107],[48.7011904,10.7937059],[48.7010630,10.7938578],[48.7006769,10.7942863],[48.7003010,10.7945588],[48.6997919,10.7949513],[48.6994049,10.7952253],[48.6992629,10.7953214],[48.6991267,10.7954146],[48.6989432,10.7955539],[48.6987972,10.7956630],[48.6988458,10.7956456],[48.6988238,10.7955185],[48.6986590,10.7953473],[48.6986168,10.7951066],[48.6986106,10.7946094],[48.6986143,10.7943716],[48.6986513,10.7941507],[48.6986949,10.7939417],[48.6987143,10.7936918],[48.6987523,10.7934861],[48.6988187,10.7934794],[48.6988532,10.7936172],[48.6988492,10.7938100],[48.6988511,10.7940464],[48.6988464,10.7941861],[48.6988335,10.7947037],[48.6988464,10.7950388],[48.6988718,10.7952735],[48.6989302,10.7958116],[48.6990249,10.7963220],[48.6991378,10.7967562],[48.6991899,10.7969421],[48.6993245,10.7973266],[48.6995492,10.7978254],[48.6996530,10.7980116],[48.6998735,10.7983696],[48.6999835,10.7985426],[48.7000706,10.7986772],[48.7001995,10.7988384],[48.7002580,10.7989468],[48.7003291,10.7990567],[48.7004806,10.7993419],[48.7006878,10.7996747],[48.7008670,10.7999924],[48.7009371,10.8001276],[48.7010622,10.8004473],[48.7011866,10.8008369],[48.7012207,10.8009805],[48.7012743,10.8011890],[48.7013472,10.8015548],[48.7014336,10.8019119],[48.7014795,10.8021278],[48.7015844,10.8026415],[48.7016330,10.8028649],[48.7017743,10.8034596],[48.7018074,10.8035992],[48.7018322,10.8037401],[48.7018955,10.8040016],[48.7019428,10.8041953],[48.7020170,10.8045105],[48.7020809,10.8048285],[48.7021341,10.8050853],[48.7022019,10.8053449],[48.7022793,10.8056564],[48.7023884,10.8060514],[48.7025515,10.8066379],[48.7026090,10.8068531],[48.7027729,10.8075129],[48.7029207,10.8080576],[48.7029799,10.8082942],[48.7030418,10.8085314],[48.7030900,10.8086995],[48.7031381,10.8088718],[48.7031907,10.8090572],[48.7032773,10.8093406],[48.7033893,10.8097185],[48.7036437,10.8104970],[48.7037086,10.8106914],[48.7037733,10.8108739],[48.7038661,10.8110947],[48.7038817,10.8112325],[48.7038386,10.8113523],[48.7039157,10.8113798],[48.7040048,10.8115246],[48.7041249,10.8117573],[48.7043187,10.8121176],[48.7045911,10.8125489],[48.7046703,10.8126733],[48.7050866,10.8132774],[48.7054777,10.8138702],[48.7058531,10.8144699],[48.7059274,10.8146044],[48.7060772,10.8148482],[48.7061610,10.8149563],[48.7062371,10.8150446],[48.7062985,10.8151516],[48.7064917,10.8155982],[48.7066088,10.8159532],[48.7067107,10.8163246],[48.7067691,10.8164996],[48.7069051,10.8169284],[48.7071876,10.8176821],[48.7074842,10.8184255],[48.7075820,10.8186854],[48.7077037,10.8192358],[48.7077840,10.8198816],[48.7078032,10.8207448],[48.7078122,10.8213179],[48.7078223,10.8216126],[48.7078312,10.8224493],[48.7078075,10.8230223],[48.7077599,10.8236773],[48.7077256,10.8240319],[48.7076429,10.8247352],[48.7076278,10.8253724],[48.7076645,10.8261999],[48.7076417,10.8264117],[48.7075495,10.8264875],[48.7074716,10.8265703],[48.7074934,10.8267838],[48.7075761,10.8271153],[48.7076925,10.8273472],[48.7078272,10.8275344],[48.7080339,10.8279420],[48.7081299,10.8281534],[48.7082115,10.8282841],[48.7083327,10.8284668],[48.7084480,10.8286458],[48.7085233,10.8287519],[48.7085902,10.8288624],[48.7086973,10.8290548],[48.7087927,10.8291604],[48.7089394,10.8293219],[48.7092097,10.8296831],[48.7093693,10.8299262],[48.7094423,10.8300206],[48.7098029,10.8305276],[48.7099215,10.8307908],[48.7100330,10.8310681],[48.7101906,10.8315995],[48.7102831,10.8321071],[48.7103221,10.8328082],[48.7103285,10.8330883],[48.7103274,10.8332745],[48.7103099,10.8334605],[48.7102775,10.8338398],[48.7102648,10.8341310],[48.7102417,10.8344084],[48.7101890,10.8352404],[48.7101668,10.8361853],[48.7101688,10.8363740],[48.7101987,10.8369538],[48.7102143,10.8372390],[48.7102453,10.8378104],[48.7102523,10.8379993],[48.7103299,10.8386437],[48.7104193,10.8392976],[48.7104596,10.8399320],[48.7104395,10.8404047],[48.7104260,10.8405919],[48.7103937,10.8409449],[48.7103194,10.8414241],[48.7102777,10.8416198],[48.7102211,10.8419843],[48.7102028,10.8421397],[48.7101043,10.8426755],[48.7099754,10.8433093],[48.7099318,10.8435502],[48.7098716,10.8438815],[48.7097194,10.8447326],[48.7095596,10.8455790],[48.7093752,10.8462068],[48.7090859,10.8469444],[48.7087954,10.8476843],[48.7085444,10.8483281],[48.7084081,10.8488997],[48.7083373,10.8491831],[48.7082893,10.8494055],[48.7082187,10.8496974],[48.7081193,10.8499809],[48.7080990,10.8501889],[48.7081043,10.8503391],[48.7081219,10.8506492],[48.7081205,10.8507871],[48.7081379,10.8510278],[48.7081886,10.8517029],[48.7081877,10.8524951],[48.7082038,10.8532680],[48.7082278,10.8541045],[48.7082509,10.8549208],[48.7082545,10.8557948],[48.7082747,10.8566476],[48.7083059,10.8576255],[48.7083112,10.8578068],[48.7083158,10.8584400],[48.7083504,10.8591159],[48.7083784,10.8599989],[48.7084089,10.8609803],[48.7084296,10.8617921],[48.7084241,10.8625024],[48.7084446,10.8629935],[48.7084682,10.8631408],[48.7084713,10.8634655],[48.7084974,10.8639637],[48.7085078,10.8644094],[48.7085046,10.8645953],[48.7085125,10.8647920],[48.7085522,10.8651914],[48.7086338,10.8660803],[48.7086606,10.8663657],[48.7087608,10.8672334],[48.7088201,10.8679701],[48.7088643,10.8683877],[48.7089474,10.8692514],[48.7090151,10.8699459],[48.7091264,10.8708221],[48.7091927,10.8711200],[48.7092113,10.8712708],[48.7092400,10.8715090],[48.7092601,10.8716663],[48.7092827,10.8718319],[48.7093214,10.8720747],[48.7093453,10.8723232],[48.7093744,10.8725723],[48.7093782,10.8727379],[48.7093795,10.8733424],[48.7093193,10.8740158],[48.7092649,10.8745267],[48.7092474,10.8746911],[48.7092001,10.8750910],[48.7091847,10.8757437],[48.7092014,10.8759689],[48.7092182,10.8762550],[48.7092375,10.8765448],[48.7092447,10.8767083],[48.7092181,10.8770990],[48.7091212,10.8774031],[48.7090361,10.8776165],[48.7088544,10.8779168],[48.7087828,10.8780304],[48.7086773,10.8782057],[48.7084442,10.8785910],[48.7083766,10.8786938],[48.7081862,10.8789123],[48.7081022,10.8789877],[48.7079774,10.8790388],[48.7078018,10.8790227],[48.7077219,10.8790726],[48.7077482,10.8791518],[48.7077327,10.8792690],[48.7077594,10.8795097],[48.7078146,10.8799024],[48.7078339,10.8800368],[48.7078710,10.8803254],[48.7079200,10.8806338],[48.7079688,10.8808751],[48.7080312,10.8813730],[48.7080611,10.8815390],[48.7081336,10.8820321],[48.7082197,10.8826296],[48.7082607,10.8832502],[48.7082492,10.8835175],[48.7082062,10.8837790],[48.7081948,10.8841285],[48.7082230,10.8843852],[48.7082861,10.8846337],[48.7085206,10.8853238],[48.7086830,10.8856956],[48.7087450,10.8858516],[48.7087811,10.8860183],[48.7088176,10.8863639],[48.7088570,10.8868823],[48.7089177,10.8873780],[48.7089402,10.8876270],[48.7089819,10.8879506],[48.7090118,10.8882827],[48.7090362,10.8885371],[48.7090177,10.8888794],[48.7089596,10.8892130],[48.7089137,10.8896360],[48.7088965,10.8898810],[48.7088829,10.8900486],[48.7088835,10.8904807],[48.7088737,10.8910773],[48.7088507,10.8915943],[48.7086337,10.8922162],[48.7084665,10.8926665],[48.7083882,10.8928864],[48.7082664,10.8931577],[48.7081464,10.8933339],[48.7080585,10.8934469],[48.7078344,10.8936883],[48.7076998,10.8938283],[48.7075673,10.8939871],[48.7072061,10.8943898],[48.7069816,10.8946467],[48.7066410,10.8949593],[48.7065299,10.8950053],[48.7064142,10.8950094],[48.7059230,10.8949654],[48.7057635,10.8949707],[48.7055992,10.8949785],[48.7054301,10.8949941],[48.7051052,10.8950158],[48.7046657,10.8950335],[48.7042673,10.8950063],[48.7038447,10.8949415],[48.7036107,10.8949405],[48.7035580,10.8950863],[48.7035805,10.8952526],[48.7036190,10.8957558],[48.7036326,10.8959407],[48.7036337,10.8962621],[48.7036221,10.8965764],[48.7036117,10.8967731],[48.7035814,10.8972267],[48.7035681,10.8974548],[48.7035527,10.8976815],[48.7035287,10.8979404],[48.7035004,10.8982004],[48.7034873,10.8983816],[48.7034727,10.8986911],[48.7034459,10.8991544],[48.7034227,10.8996970],[48.7035101,10.8997152],[48.7036966,10.8996092],[48.7037152,10.8994189],[48.7036334,10.8993488],[48.7033626,10.8993224],[48.7032647,10.8993588],[48.7031217,10.8994439],[48.7031393,10.8997539],[48.7030670,10.9000706],[48.7029918,10.9004255],[48.7028821,10.9007502],[48.7027734,10.9011087],[48.7025821,10.9016666],[48.7023100,10.9023167],[48.7022332,10.9025075],[48.7021329,10.9027066],[48.7018681,10.9032725],[48.7018068,10.9033850],[48.7016850,10.9036771],[48.7016156,10.9038473],[48.7015434,10.9039752],[48.7014666,10.9040989],[48.7012144,10.9045523],[48.7009520,10.9048693],[48.7006013,10.9052004],[48.7005067,10.9052731],[48.7003564,10.9053744],[48.6999866,10.9055951],[48.6997216,10.9057358],[48.6996177,10.9057939],[48.6992107,10.9060146],[48.6986990,10.9062978],[48.6982146,10.9065546],[48.6981480,10.9066032],[48.6981205,10.9065674],[48.6978415,10.9066248],[48.6976363,10.9067405],[48.6973672,10.9069302],[48.6971467,10.9070821],[48.6969790,10.9071812],[48.6967238,10.9073511],[48.6965743,10.9075770],[48.6964139,10.9076349],[48.6961668,10.9077265],[48.6960367,10.9078042],[48.6959453,10.9078502],[48.6955785,10.9080296],[48.6951284,10.9082677],[48.6947728,10.9084486],[48.6945705,10.9085556],[48.6942755,10.9086974],[48.6940747,10.9088099],[48.6939212,10.9088941],[48.6935609,10.9090989],[48.6932028,10.9093068],[48.6928453,10.9095227],[48.6924424,10.9099283],[48.6922696,10.9102336],[48.6922069,10.9103440],[48.6921470,10.9105181],[48.6920672,10.9108886],[48.6919157,10.9113634],[48.6918285,10.9116419],[48.6916882,10.9120531],[48.6915820,10.9123882],[48.6915008,10.9126399],[48.6914021,10.9128921],[48.6913324,10.9130073],[48.6911804,10.9131398],[48.6909723,10.9131239],[48.6908095,10.9130748],[48.6905971,10.9130239],[48.6904804,10.9130498],[48.6903759,10.9131087],[48.6902074,10.9132340],[48.6900667,10.9133373],[48.6899237,10.9134882],[48.6897772,10.9137393],[48.6897612,10.9139693],[48.6898381,10.9143951],[48.6899401,10.9148313],[48.6899931,10.9150583],[48.6900312,10.9152425],[48.6900730,10.9155777],[48.6901022,10.9156806],[48.6901361,10.9158245],[48.6901572,10.9159559],[48.6902262,10.9160123],[48.6901976,10.9160014],[48.6901401,10.9159889],[48.6900785,10.9159772],[48.6901310,10.9161066],[48.6902039,10.9162699],[48.6902309,10.9165740],[48.6902419,10.9167272],[48.6902710,10.9169071],[48.6902801,10.9171308],[48.6902899,10.9173177],[48.6903247,10.9177724],[48.6903431,10.9180416],[48.6903482,10.9183754],[48.6903619,10.9185599],[48.6904008,10.9191535],[48.6903311,10.9191046],[48.6903672,10.9189552],[48.6903956,10.9190820],[48.6904179,10.9191980],[48.6904291,10.9194151],[48.6904110,10.9196176],[48.6904422,10.9198652],[48.6904454,10.9200674],[48.6905023,10.9203893],[48.6905935,10.9209287],[48.6905972,10.9212390],[48.6905954,10.9214523],[48.6905779,10.9217669],[48.6905752,10.9220174],[48.6906172,10.9223733],[48.6906622,10.9226888],[48.6906902,10.9228267],[48.6907244,10.9230379],[48.6907730,10.9232052],[48.6908150,10.9233974],[48.6909099,10.9238822],[48.6909908,10.9244268],[48.6909918,10.9247901],[48.6909780,10.9249342],[48.6909520,10.9251265],[48.6909339,10.9254967],[48.6908831,10.9258987],[48.6908512,10.9261620],[48.6908217,10.9264193],[48.6908194,10.9266831],[48.6908112,10.9268782],[48.6907875,10.9270727],[48.6907716,10.9272723],[48.6907553,10.9275445],[48.6907448,10.9279380],[48.6907214,10.9285152],[48.6907130,10.9287299],[48.6906966,10.9290231],[48.6906836,10.9293181],[48.6907138,10.9295173],[48.6907260,10.9298876],[48.6907192,10.9305236],[48.6906962,10.9310833],[48.6906895,10.9313096],[48.6906813,10.9314489],[48.6906792,10.9315893],[48.6907028,10.9320980],[48.6907095,10.9322484],[48.6907498,10.9327103],[48.6907789,10.9329310],[48.6908373,10.9333725],[48.6908649,10.9335692],[48.6909553,10.9341861],[48.6910561,10.9348795],[48.6911601,10.9357182],[48.6912267,10.9364230],[48.6912438,10.9369310],[48.6912615,10.9370978],[48.6912055,10.9371789],[48.6911630,10.9373046],[48.6911721,10.9375676],[48.6912111,10.9381117],[48.6912558,10.9384952],[48.6913168,10.9388504],[48.6914240,10.9392373],[48.6915377,10.9395323],[48.6916350,10.9397658],[48.6917168,10.9399343],[48.6919403,10.9403919],[48.6920615,10.9406271],[48.6922995,10.9411186],[48.6925282,10.9415734],[48.6926344,10.9417832],[48.6927080,10.9419397],[48.6928339,10.9421918],[48.6929240,10.9423695],[48.6931151,10.9427359],[48.6932082,10.9429229],[48.6934896,10.9434784],[48.6938583,10.9441449],[48.6940782,10.9445966],[48.6941341,10.9447071],[48.6942388,10.9448030],[48.6943141,10.9446361],[48.6944420,10.9446194],[48.6945941,10.9446380],[48.6946905,10.9446583],[48.6948360,10.9446991],[48.6951241,10.9448078],[48.6952178,10.9448397],[48.6954504,10.9449288],[48.6955456,10.9449667],[48.6956984,10.9450390],[48.6958697,10.9451049],[48.6961326,10.9451374],[48.6962788,10.9451530],[48.6962674,10.9451148],[48.6962884,10.9451434],[48.6963719,10.9452146],[48.6964149,10.9452642],[48.6963418,10.9451390],[48.6962712,10.9451317],[48.6962916,10.9450765],[48.6962408,10.9451402],[48.6963159,10.9451063],[48.6964164,10.9451464],[48.6965323,10.9451477],[48.6967402,10.9451746],[48.6968355,10.9452023],[48.6969345,10.9452192],[48.6970380,10.9452472],[48.6974050,10.9453260],[48.6976355,10.9453912],[48.6978848,10.9454467],[48.6980323,10.9454865],[48.6981869,10.9455373],[48.6984658,10.9456119],[48.6985947,10.9456368],[48.6987772,10.9456102],[48.6988718,10.9455746],[48.6990249,10.9455188],[48.6992498,10.9454332],[48.6993677,10.9455040],[48.6994540,10.9458572],[48.6995088,10.9460470],[48.6995540,10.9461905],[48.6996535,10.9464772],[48.6997045,10.9466374],[48.6997881,10.9468843],[48.6999765,10.9474443],[48.7001890,10.9480920],[48.7002914,10.9484772],[48.7003302,10.9486621],[48.7003678,10.9488474],[48.7004326,10.9491642],[48.7004614,10.9493498],[48.7005103,10.9496032],[48.7005920,10.9500549],[48.7006829,10.9504501],[48.7007151,10.9510184],[48.7007336,10.9512770],[48.7007501,10.9515989],[48.7007619,10.9517456],[48.7007895,10.9522403],[48.7008228,10.9531037],[48.7008482,10.9536869],[48.7008120,10.9542751],[48.7007745,10.9548625],[48.7007330,10.9551098],[48.7007031,10.9553576],[48.7006883,10.9557031],[48.7006855,10.9558825],[48.7006967,10.9562630],[48.7007155,10.9564554],[48.7007662,10.9567383],[48.7008650,10.9571961],[48.7008987,10.9573720],[48.7009200,10.9575339],[48.7009271,10.9577767],[48.7008702,10.9580895],[48.7008192,10.9583646],[48.7007953,10.9585199],[48.7007677,10.9586714],[48.7007353,10.9588182],[48.7006880,10.9591185],[48.7006424,10.9595080],[48.7006247,10.9597481],[48.7005878,10.9601183],[48.7006107,10.9607210],[48.7006693,10.9612115],[48.7007315,10.9616935],[48.7008335,10.9623696],[48.7008273,10.9632206],[48.7008223,10.9636771],[48.7008277,10.9638473],[48.7008329,10.9641078],[48.7008182,10.9646128],[48.7007939,10.9654237],[48.7007866,10.9659138],[48.7007791,10.9662236],[48.7007910,10.9664399],[48.7008336,10.9671578],[48.7008475,10.9674533],[48.7008453,10.9676436],[48.7008516,10.9678300],[48.7008423,10.9680216],[48.7007698,10.9685960],[48.7007589,10.9687911],[48.7006921,10.9690886],[48.7007125,10.9694501],[48.7007437,10.9698333],[48.7007543,10.9699756],[48.7007628,10.9701224],[48.7007759,10.9703396],[48.7007859,10.9705562],[48.7008137,10.9708974],[48.7008450,10.9712533],[48.7008873,10.9713912],[48.7009636,10.9717149],[48.7009009,10.9723457],[48.7008040,10.9729814],[48.7007539,10.9733384],[48.7007083,10.9735114],[48.7005701,10.9739281],[48.7004987,10.9740730],[48.7002943,10.9744576],[48.7001958,10.9746241],[48.7001062,10.9747756],[48.7000296,10.9749328],[48.6999518,10.9750810],[48.6996812,10.9754529],[48.6995764,10.9755976],[48.6994853,10.9757606],[48.6993722,10.9758771],[48.6991207,10.9761324],[48.6987885,10.9764663],[48.6987074,10.9765499],[48.6985716,10.9767190],[48.6986273,10.9771299],[48.6986743,10.9773094],[48.6986819,10.9774464],[48.6987290,10.9777208],[48.6988283,10.9780621],[48.6989386,10.9783496],[48.6990483,10.9785529],[48.6992591,10.9789588],[48.6994914,10.9793631],[48.6996115,10.9795672],[48.6997628,10.9798404],[48.6998267,10.9799867],[48.6998795,10.9801445],[48.6999480,10.9803939],[48.6999812,10.9805634],[48.7000488,10.9808309],[48.7000824,10.9809826],[48.7001407,10.9810959],[48.7002180,10.9812967],[48.7002630,10.9814506],[48.7003892,10.9818143],[48.7004225,10.9820231],[48.7004285,10.9822616],[48.7004297,10.9824986],[48.7004203,10.9827345],[48.7002862,10.9835015],[48.7001931,10.9840029],[48.7000945,10.9846597],[48.7000451,10.9850433],[48.7000029,10.9853459],[48.6999037,10.9861585],[48.6998421,10.9867409],[48.6997678,10.9876261],[48.6996680,10.9882703],[48.6995670,10.9890114],[48.6995359,10.9893397],[48.6995182,10.9899359],[48.6995367,10.9901403],[48.6995527,10.9903270],[48.6995897,10.9906273],[48.6996411,10.9907913],[48.6996788,10.9909261],[48.6997270,10.9912626],[48.6998578,10.9916038],[48.7000150,10.9920040],[48.7001132,10.9922282],[48.7002061,10.9923781],[48.7003177,10.9925187],[48.7004163,10.9926886],[48.7004877,10.9930050],[48.7005564,10.9933713],[48.7005864,10.9935272],[48.7006335,10.9936645],[48.7006926,10.9939434],[48.7007033,10.9941778],[48.7006770,10.9944063],[48.7006534,10.9945492],[48.7006086,10.9947196],[48.7005539,10.9949124],[48.7005279,10.9951005],[48.7005414,10.9952756],[48.7005875,10.9955086],[48.7006221,10.9957694],[48.7006843,10.9961639],[48.7007698,10.9965541],[48.7008401,10.9969362],[48.7008649,10.9970857],[48.7009618,10.9976415],[48.7010122,10.9979534],[48.7010206,10.9981468],[48.7010632,10.9984263],[48.7011278,10.9990550],[48.7011487,10.9992727],[48.7011780,10.9995064],[48.7011925,11.0002005],[48.7011982,11.0008095],[48.7012009,11.0011479],[48.7012019,11.0015263],[48.7012093,11.0021260],[48.7012085,11.0024381],[48.7011930,11.0026357],[48.7011868,11.0027756],[48.7011730,11.0034265],[48.7011718,11.0037269],[48.7011663,11.0039502],[48.7011742,11.0043164],[48.7011777,11.0045314],[48.7011863,11.0049504],[48.7011604,11.0052174],[48.7011652,11.0053543],[48.7011504,11.0055533],[48.7011619,11.0057280],[48.7011590,11.0059880],[48.7011991,11.0063106],[48.7011424,11.0069422],[48.7011109,11.0074670],[48.7010853,11.0076160],[48.7010597,11.0080138],[48.7010511,11.0085254],[48.7010552,11.0086646],[48.7010573,11.0088008],[48.7010631,11.0089973],[48.7010577,11.0091757],[48.7010480,11.0094834],[48.7010691,11.0097193],[48.7010864,11.0101121],[48.7011047,11.0106451],[48.7011192,11.0108666],[48.7011583,11.0111977],[48.7011928,11.0116613],[48.7012164,11.0119973],[48.7012176,11.0122151],[48.7011913,11.0126081],[48.7011480,11.0127968],[48.7009989,11.0134519],[48.7008449,11.0142609],[48.7007654,11.0146045],[48.7007230,11.0147667],[48.7006688,11.0149966],[48.7006340,11.0151387],[48.7006030,11.0152734],[48.7005515,11.0154591],[48.7005050,11.0157065],[48.7005161,11.0159516],[48.7004902,11.0161260],[48.7004766,11.0165534],[48.7004522,11.0167871],[48.7004527,11.0171569],[48.7004494,11.0174271],[48.7004310,11.0177366],[48.7004104,11.0180783],[48.7003939,11.0183742],[48.7003763,11.0186999],[48.7003432,11.0190149],[48.7002830,11.0193898],[48.7002032,11.0197448],[48.7000983,11.0202788],[48.7000964,11.0207349],[48.7001543,11.0210934],[48.7002119,11.0213574],[48.7002765,11.0216284],[48.7004010,11.0221304],[48.7005784,11.0227779],[48.7006306,11.0229193],[48.7007048,11.0232006],[48.7008865,11.0239464],[48.7009507,11.0241831],[48.7009969,11.0243463],[48.7010705,11.0245843],[48.7012930,11.0253225],[48.7014183,11.0257293],[48.7015354,11.0261111],[48.7016717,11.0264901],[48.7017139,11.0266136],[48.7018139,11.0269318],[48.7019117,11.0272359],[48.7019608,11.0273578],[48.7021108,11.0278601],[48.7021507,11.0279912],[48.7022184,11.0281294],[48.7022964,11.0283352],[48.7023895,11.0286151],[48.7024401,11.0287858],[48.7025093,11.0289586],[48.7026068,11.0292629],[48.7027394,11.0297255],[48.7029176,11.0301766],[48.7029807,11.0302770],[48.7031111,11.0304681],[48.7033133,11.0307230],[48.7035288,11.0309232],[48.7037610,11.0310819],[48.7039755,11.0312788],[48.7042983,11.0317945],[48.7043619,11.0319764],[48.7044084,11.0321722],[48.7044689,11.0325832],[48.7044746,11.0327774],[48.7044782,11.0330128],[48.7045567,11.0331416],[48.7046409,11.0332374],[48.7047782,11.0333524],[48.7048636,11.0334330],[48.7047921,11.0333638],[48.7046487,11.0332375],[48.7045269,11.0331597],[48.7044065,11.0331469],[48.7043264,11.0332825],[48.7042048,11.0335952],[48.7041460,11.0337735],[48.7040063,11.0340924],[48.7039466,11.0342451],[48.7038620,11.0345744],[48.7038426,11.0349515],[48.7039079,11.0353855],[48.7040306,11.0357222],[48.7041077,11.0359104],[48.7041732,11.0361084],[48.7042453,11.0363331],[48.7042736,11.0364802],[48.7043347,11.0367725],[48.7043612,11.0371909],[48.7043575,11.0376090],[48.7043623,11.0380449],[48.7043698,11.0382478],[48.7043868,11.0385675],[48.7044189,11.0392453],[48.7043775,11.0394761],[48.7043669,11.0398207],[48.7044066,11.0403872],[48.7044401,11.0411066],[48.7045099,11.0418876],[48.7045433,11.0420975],[48.7046465,11.0425821],[48.7047911,11.0432413],[48.7049633,11.0438753],[48.7051249,11.0444166],[48.7052098,11.0446990],[48.7053454,11.0450818],[48.7054709,11.0453152],[48.7056536,11.0455120],[48.7057499,11.0456421],[48.7060901,11.0461012],[48.7061500,11.0462066],[48.7062665,11.0464182],[48.7065406,11.0468317],[48.7068594,11.0473286],[48.7072755,11.0479285],[48.7073505,11.0480340],[48.7076884,11.0485132],[48.7078836,11.0487977],[48.7079880,11.0490019],[48.7082230,11.0496135],[48.7082772,11.0497731],[48.7085383,11.0505380],[48.7087410,11.0511181],[48.7088272,11.0512647],[48.7088730,11.0514230],[48.7089496,11.0519855],[48.7089792,11.0523539],[48.7089785,11.0526836],[48.7089611,11.0529182],[48.7088673,11.0534118],[48.7087254,11.0539071],[48.7086751,11.0540795],[48.7085946,11.0543225],[48.7084835,11.0546481],[48.7083506,11.0550637],[48.7082830,11.0553078],[48.7082915,11.0554468],[48.7085148,11.0556849],[48.7088323,11.0559921],[48.7088933,11.0561775],[48.7088207,11.0563781],[48.7087917,11.0565244],[48.7088339,11.0567431],[48.7089305,11.0568406],[48.7093195,11.0570435],[48.7094400,11.0571817],[48.7095229,11.0573896],[48.7095573,11.0576161],[48.7096256,11.0579519],[48.7096998,11.0581514],[48.7097854,11.0583370],[48.7099521,11.0585668],[48.7102284,11.0588589],[48.7104803,11.0590104],[48.7106122,11.0590747],[48.7107689,11.0591269],[48.7107464,11.0591396],[48.7106550,11.0591331],[48.7106441,11.0591962],[48.7107244,11.0591112],[48.7108334,11.0591017],[48.7109290,11.0591490],[48.7111657,11.0592018],[48.7113452,11.0592809],[48.7115071,11.0593845],[48.7116714,11.0595653],[48.7117822,11.0597687],[48.7119854,11.0600521],[48.7120893,11.0603554],[48.7121785,11.0605386],[48.7122590,11.0608582],[48.7123621,11.0610399],[48.7123736,11.0612462],[48.7123554,11.0614108],[48.7123896,11.0618259],[48.7124219,11.0620701],[48.7124937,11.0624573],[48.7125729,11.0629046],[48.7125901,11.0630494],[48.7125919,11.0633032],[48.7125860,11.0635654],[48.7125678,11.0640238],[48.7125487,11.0643450],[48.7124981,11.0647713],[48.7124896,11.0651456],[48.7124603,11.0654572],[48.7124342,11.0656090],[48.7124152,11.0660250],[48.7123965,11.0662198],[48.7123929,11.0664243],[48.7123971,11.0666190],[48.7124167,11.0668309],[48.7124040,11.0670744],[48.7124017,11.0674636],[48.7123951,11.0678903],[48.7124556,11.0681399],[48.7124598,11.0684403],[48.7125336,11.0688320],[48.7125818,11.0690924],[48.7126291,11.0693526],[48.7127301,11.0697466],[48.7127954,11.0699855],[48.7129938,11.0706698],[48.7132180,11.0712624],[48.7133025,11.0714412],[48.7133817,11.0716217],[48.7137264,11.0722173],[48.7139891,11.0726798],[48.7141521,11.0729787],[48.7143055,11.0732152],[48.7143950,11.0733525],[48.7144912,11.0734856],[48.7145770,11.0736199],[48.7146902,11.0737929],[48.7147629,11.0741177],[48.7148046,11.0743727],[48.7148202,11.0745619],[48.7148328,11.0747259],[48.7148514,11.0748869],[48.7148866,11.0751734],[48.7149177,11.0753818],[48.7149513,11.0755633],[48.7149875,11.0757499],[48.7150180,11.0759172],[48.7150432,11.0761547],[48.7150623,11.0764083],[48.7151121,11.0766982],[48.7151465,11.0769414],[48.7152482,11.0775358],[48.7153608,11.0780500],[48.7154139,11.0782976],[48.7154829,11.0786931],[48.7155357,11.0792486],[48.7155675,11.0795376],[48.7156584,11.0803311],[48.7156970,11.0807327],[48.7157999,11.0816019],[48.7157934,11.0821719],[48.7157291,11.0828055],[48.7156889,11.0833870],[48.7157185,11.0841392],[48.7158103,11.0847476],[48.7158891,11.0851907],[48.7159392,11.0854176],[48.7159624,11.0855598],[48.7159933,11.0857458],[48.7160247,11.0859164],[48.7160738,11.0861107],[48.7161174,11.0863089],[48.7161454,11.0865127],[48.7161749,11.0866694],[48.7162129,11.0868480],[48.7162479,11.0870033],[48.7163764,11.0871203],[48.7165144,11.0871655],[48.7166818,11.0871245],[48.7168211,11.0870748],[48.7170276,11.0870413],[48.7171170,11.0871249],[48.7171543,11.0872550],[48.7171508,11.0874259],[48.7170906,11.0876034],[48.7170451,11.0878110],[48.7170530,11.0880484],[48.7171444,11.0887222],[48.7172205,11.0891098],[48.7172559,11.0892929],[48.7173674,11.0897207],[48.7176135,11.0904725],[48.7178885,11.0911089],[48.7180015,11.0913243],[48.7181353,11.0916178],[48.7182092,11.0919376],[48.7183014,11.0923227],[48.7183761,11.0926098],[48.7184883,11.0928353],[48.7187491,11.0931830],[48.7188369,11.0933941],[48.7188745,11.0935670],[48.7189142,11.0939316],[48.7189654,11.0941070],[48.7190646,11.0942553],[48.7191894,11.0943447],[48.7193194,11.0944016],[48.7194600,11.0944423],[48.7196531,11.0944729],[48.7198406,11.0945025],[48.7199527,11.0945382],[48.7201362,11.0947465],[48.7201883,11.0949015],[48.7202169,11.0950701],[48.7202692,11.0956359],[48.7202851,11.0959357],[48.7203007,11.0962157],[48.7203422,11.0964512],[48.7204122,11.0966365],[48.7204540,11.0971112],[48.7205013,11.0975986],[48.7205269,11.0978902],[48.7205650,11.0982025],[48.7206075,11.0985510],[48.7206472,11.0989333],[48.7206670,11.0990756],[48.7206768,11.0992550],[48.7207034,11.0994753],[48.7207226,11.0998312],[48.7207607,11.1001534],[48.7208087,11.1004831],[48.7208131,11.1007020],[48.7208209,11.1009024],[48.7208372,11.1012689],[48.7208516,11.1015243],[48.7208541,11.1017141],[48.7208672,11.1019591],[48.7208569,11.1022430],[48.7208400,11.1023794],[48.7208061,11.1027463],[48.7207722,11.1029755],[48.7207510,11.1031501],[48.7207187,11.1033826],[48.7206873,11.1036570],[48.7206292,11.1040442],[48.7205694,11.1043545],[48.7204915,11.1047187],[48.7204304,11.1051603],[48.7203817,11.1053402],[48.7203300,11.1055440],[48.7202613,11.1057175],[48.7202335,11.1058277],[48.7201960,11.1060017],[48.7201433,11.1062120],[48.7201051,11.1064249],[48.7200590,11.1067285],[48.7199864,11.1070919],[48.7199477,11.1072233],[48.7199000,11.1073486],[48.7197179,11.1081198],[48.7196491,11.1084030],[48.7196082,11.1086250],[48.7195890,11.1089346],[48.7195969,11.1091710],[48.7196083,11.1093491],[48.7196036,11.1096625],[48.7195858,11.1099982],[48.7196147,11.1101996],[48.7197528,11.1102456],[48.7199380,11.1103244],[48.7201274,11.1103695],[48.7202113,11.1104724],[48.7202590,11.1106074],[48.7202759,11.1109464],[48.7202640,11.1111116],[48.7202655,11.1112853],[48.7202726,11.1115703],[48.7202834,11.1117651],[48.7202734,11.1120161],[48.7202737,11.1121562],[48.7203986,11.1123641],[48.7204604,11.1126145],[48.7203694,11.1127114],[48.7202686,11.1127898],[48.7202386,11.1129665],[48.7201734,11.1131403],[48.7201346,11.1132878],[48.7200796,11.1133917],[48.7199429,11.1133446],[48.7198395,11.1132925],[48.7196680,11.1132585],[48.7195003,11.1132582],[48.7194145,11.1133128],[48.7194361,11.1135347],[48.7194368,11.1137833],[48.7194683,11.1140606],[48.7195084,11.1143988],[48.7195632,11.1146663],[48.7196163,11.1149683],[48.7196746,11.1151782],[48.7197321,11.1152741],[48.7197419,11.1154416],[48.7198191,11.1158125],[48.7198917,11.1161768],[48.7199302,11.1163619],[48.7199688,11.1165548],[48.7200282,11.1168529],[48.7200610,11.1170269],[48.7201146,11.1172857],[48.7201554,11.1174893],[48.7202566,11.1179093],[48.7202800,11.1180494],[48.7203858,11.1185632],[48.7204130,11.1187127],[48.7204628,11.1192172],[48.7205012,11.1193985],[48.7205381,11.1195846],[48.7206562,11.1201161],[48.7207681,11.1205741],[48.7208690,11.1209642],[48.7209597,11.1214339],[48.7209983,11.1216318],[48.7211207,11.1220877],[48.7211941,11.1223331],[48.7212416,11.1225174],[48.7214096,11.1230656],[48.7214580,11.1232735],[48.7214866,11.1234618],[48.7214132,11.1236089],[48.7212895,11.1236821],[48.7210494,11.1238676],[48.7209789,11.1239938],[48.7209648,11.1241559],[48.7210346,11.1243685],[48.7211736,11.1246952],[48.7212311,11.1248014],[48.7212896,11.1249120],[48.7213540,11.1250231],[48.7214209,11.1251303],[48.7214907,11.1252362],[48.7216295,11.1254352],[48.7217613,11.1255851],[48.7218800,11.1256881],[48.7219625,11.1257928],[48.7220107,11.1259924],[48.7220868,11.1262073],[48.7221465,11.1263741],[48.7222288,11.1266563],[48.7222854,11.1268745],[48.7223383,11.1271000],[48.7223922,11.1273493],[48.7224486,11.1276037],[48.7224998,11.1278633],[48.7225304,11.1279960],[48.7225655,11.1281266],[48.7226342,11.1283940],[48.7227120,11.1288311],[48.7228034,11.1292879],[48.7228834,11.1297731],[48.7229061,11.1299395],[48.7229988,11.1306014],[48.7230666,11.1310814],[48.7231324,11.1315399],[48.7231739,11.1318392],[48.7232236,11.1321287],[48.7232475,11.1322718],[48.7233454,11.1328282],[48.7234253,11.1332371],[48.7234586,11.1333662],[48.7236713,11.1340835],[48.7238898,11.1346647],[48.7240179,11.1349638],[48.7241568,11.1353105],[48.7242659,11.1355252],[48.7243662,11.1356683],[48.7244915,11.1358720],[48.7245682,11.1360119],[48.7246216,11.1361655],[48.7246822,11.1363479],[48.7247302,11.1365475],[48.7247692,11.1366877],[48.7248268,11.1368038],[48.7248929,11.1369541],[48.7250258,11.1371720],[48.7251373,11.1373042],[48.7252048,11.1374203],[48.7252474,11.1375956],[48.7252962,11.1377340],[48.7253193,11.1378762],[48.7253595,11.1380157],[48.7253843,11.1381407],[48.7254000,11.1382909],[48.7254750,11.1384297],[48.7254948,11.1385772],[48.7255453,11.1387652],[48.7256529,11.1389197],[48.7257082,11.1390945],[48.7257383,11.1392619],[48.7257653,11.1395027],[48.7257781,11.1397416],[48.7257762,11.1398946],[48.7258047,11.1400656],[48.7258280,11.1403613],[48.7258099,11.1405941],[48.7257669,11.1408925],[48.7257211,11.1410611],[48.7257166,11.1412085],[48.7257134,11.1414171],[48.7256916,11.1415987],[48.7256665,11.1417707],[48.7256602,11.1419807],[48.7256618,11.1421746],[48.7256195,11.1423845],[48.7256112,11.1425217],[48.7256065,11.1426942],[48.7256109,11.1429449],[48.7256125,11.1430989],[48.7256475,11.1434231],[48.7256669,11.1435918],[48.7256697,11.1437480],[48.7257099,11.1439121],[48.7257229,11.1440719],[48.7257606,11.1442622],[48.7257990,11.1444405],[48.7258275,11.1446256],[48.7258508,11.1447645],[48.7259501,11.1449077],[48.7260805,11.1452249],[48.7261474,11.1453519],[48.7262328,11.1454875],[48.7262708,11.1456185],[48.7263693,11.1458661],[48.7265412,11.1461383],[48.7266324,11.1463525],[48.7266988,11.1464653],[48.7267506,11.1466548],[48.7269180,11.1469261],[48.7269863,11.1471147],[48.7270515,11.1472422],[48.7272225,11.1476147],[48.7273041,11.1478576],[48.7273720,11.1480181],[48.7275079,11.1483192],[48.7276688,11.1486450],[48.7277910,11.1489386],[48.7279092,11.1492619],[48.7279904,11.1494542],[48.7280625,11.1496065],[48.7281481,11.1497832],[48.7281871,11.1498779],[48.7282527,11.1500275],[48.7283305,11.1502383],[48.7284279,11.1505140],[48.7285393,11.1507584],[48.7287253,11.1512343],[48.7288151,11.1514666],[48.7289407,11.1518788],[48.7291200,11.1524949],[48.7292311,11.1530202],[48.7293592,11.1536326],[48.7294587,11.1542093],[48.7295421,11.1547024],[48.7296270,11.1552075],[48.7296568,11.1554433],[48.7296912,11.1556504],[48.7297430,11.1559082],[48.7297828,11.1561457],[48.7298383,11.1562868],[48.7298726,11.1564440],[48.7298804,11.1566196],[48.7299554,11.1571989],[48.7299861,11.1573966],[48.7300525,11.1577786],[48.7300856,11.1579960],[48.7301279,11.1582184],[48.7302087,11.1585534],[48.7302706,11.1587643],[48.7304750,11.1593346],[48.7305284,11.1595335],[48.7306892,11.1600401],[48.7307541,11.1602646],[48.7308132,11.1605084],[48.7309079,11.1608894],[48.7309382,11.1610186],[48.7310487,11.1615360],[48.7311602,11.1619164],[48.7312726,11.1622853],[48.7313940,11.1626290],[48.7314794,11.1628496],[48.7318142,11.1636635],[48.7321415,11.1643767],[48.7322623,11.1646126],[48.7324923,11.1650673],[48.7326815,11.1654328],[48.7327864,11.1656426],[48.7329597,11.1659697],[48.7330938,11.1662225],[48.7333006,11.1666411],[48.7333927,11.1669094],[48.7334939,11.1672133],[48.7335502,11.1673228],[48.7336039,11.1674876],[48.7336375,11.1676155],[48.7336434,11.1678347],[48.7337069,11.1680639],[48.7337774,11.1683417],[48.7338736,11.1686623],[48.7339850,11.1690620],[48.7340133,11.1692062],[48.7340733,11.1695156],[48.7341289,11.1698393],[48.7341778,11.1701632],[48.7342458,11.1706393],[48.7343150,11.1711367],[48.7343317,11.1712972],[48.7343497,11.1714566],[48.7343975,11.1719081],[48.7344099,11.1720510],[48.7344257,11.1723351],[48.7344234,11.1727588],[48.7344194,11.1730332],[48.7344181,11.1738186],[48.7343971,11.1745595],[48.7344035,11.1751033],[48.7344287,11.1752620],[48.7344819,11.1756153],[48.7345492,11.1759475],[48.7346036,11.1763788],[48.7346026,11.1765635],[48.7346163,11.1767129],[48.7346326,11.1768841],[48.7346311,11.1770367],[48.7346496,11.1773872],[48.7346410,11.1776312],[48.7346344,11.1779342],[48.7346262,11.1781392],[48.7346161,11.1786661],[48.7346140,11.1788308],[48.7345989,11.1789863],[48.7345539,11.1793035],[48.7345197,11.1794674],[48.7345026,11.1796504],[48.7345493,11.1798146],[48.7346276,11.1799118],[48.7347134,11.1799942],[48.7348224,11.1801406],[48.7348953,11.1802331],[48.7350512,11.1804361],[48.7351717,11.1806144],[48.7352385,11.1807123],[48.7353362,11.1808483],[48.7355407,11.1811184],[48.7356329,11.1812028],[48.7357829,11.1812976],[48.7359332,11.1814277],[48.7360632,11.1815591],[48.7361592,11.1816077],[48.7362560,11.1817794],[48.7362658,11.1819260],[48.7362200,11.1822090],[48.7361716,11.1824760],[48.7361199,11.1828071],[48.7361392,11.1830320],[48.7361246,11.1831776],[48.7361076,11.1833688],[48.7360558,11.1836798],[48.7360225,11.1838425],[48.7359893,11.1839701],[48.7359881,11.1839722],[48.7360785,11.1839971]],\r\n\t\t\t\t\tgraphDist          : [0.00,0.01,0.05,0.07,0.09,0.10,0.13,0.14,0.15,0.18,0.21,0.24,0.27,0.29,0.30,0.32,0.34,0.36,0.38,0.42,0.46,0.48,0.50,0.54,0.57,0.62,0.66,0.67,0.71,0.72,0.73,0.75,0.78,0.79,0.80,0.82,0.84,0.89,0.94,0.98,1.03,1.09,1.12,1.16,1.20,1.21,1.22,1.23,1.24,1.26,1.28,1.30,1.34,1.37,1.42,1.46,1.47,1.52,1.55,1.57,1.60,1.62,1.65,1.71,1.75,1.78,1.80,1.85,1.90,1.94,1.96,1.97,1.99,2.00,2.01,2.02,2.04,2.05,2.09,2.16,2.22,2.28,2.30,2.32,2.34,2.36,2.41,2.46,2.52,2.57,2.62,2.67,2.68,2.74,2.75,2.77,2.82,2.88,2.89,2.93,2.98,3.00,3.04,3.05,3.12,3.18,3.23,3.27,3.31,3.35,3.37,3.39,3.42,3.47,3.52,3.56,3.57,3.61,3.65,3.68,3.71,3.73,3.78,3.80,3.83,3.85,3.86,3.90,3.96,3.98,3.99,4.02,4.04,4.07,4.08,4.10,4.11,4.13,4.14,4.16,4.19,4.20,4.24,4.28,4.31,4.32,4.36,4.37,4.41,4.46,4.51,4.52,4.59,4.61,4.62,4.66,4.67,4.69,4.74,4.79,4.85,4.87,4.89,4.91,4.92,4.96,4.97,4.99,5.00,5.01,5.02,5.03,5.05,5.07,5.10,5.15,5.22,5.27,5.34,5.41,5.48,5.54,5.61,5.63,5.68,5.74,5.76,5.79,5.81,5.83,5.85,5.87,5.90,5.91,5.92,5.93,5.95,5.98,5.99,6.01,6.02,6.04,6.07,6.09,6.12,6.14,6.17,6.20,6.25,6.29,6.34,6.36,6.38,6.41,6.45,6.47,6.49,6.51,6.54,6.56,6.58,6.62,6.65,6.71,6.73,6.74,6.76,6.77,6.79,6.81,6.85,6.87,6.89,6.91,6.95,6.98,7.00,7.04,7.05,7.10,7.14,7.20,7.22,7.25,7.29,7.30,7.31,7.37,7.38,7.40,7.43,7.46,7.49,7.50,7.52,7.54,7.56,7.58,7.59,7.64,7.66,7.68,7.73,7.77,7.82,7.83,7.85,7.87,7.89,7.93,7.96,7.99,8.04,8.07,8.10,8.12,8.14,8.15,8.17,8.18,8.19,8.25,8.29,8.32,8.35,8.37,8.42,8.43,8.44,8.46,8.47,8.48,8.51,8.54,8.55,8.57,8.60,8.65,8.69,8.71,8.72,8.75,8.78,8.81,8.87,8.94,9.00,9.02,9.08,9.09,9.12,9.17,9.18,9.21,9.23,9.24,9.25,9.30,9.35,9.41,9.46,9.51,9.58,9.64,9.68,9.72,9.75,9.80,9.85,9.87,9.88,9.90,9.94,9.95,9.96,9.98,9.99,10.04,10.09,10.12,10.15,10.18,10.24,10.30,10.34,10.37,10.40,10.42,10.48,10.49,10.51,10.56,10.58,10.60,10.62,10.65,10.68,10.70,10.72,10.76,10.79,10.80,10.84,10.86,10.88,10.92,10.95,10.96,10.97,10.98,11.00,11.02,11.04,11.06,11.07,11.10,11.12,11.16,11.18,11.22,11.25,11.27,11.29,11.30,11.35,11.40,11.42,11.45,11.47,11.48,11.54,11.56,11.58,11.65,11.67,11.70,11.73,11.76,11.79,11.81,11.83,11.84,11.89,11.91,11.94,11.96,11.98,11.99,12.01,12.03,12.06,12.09,12.10,12.15,12.20,12.23,12.26,12.30,12.31,12.33,12.34,12.35,12.37,12.40,12.43,12.45,12.49,12.55,12.61,12.65,12.67,12.68,12.72,12.78,12.83,12.84,12.88,12.91,12.94,12.97,13.01,13.03,13.08,13.11,13.17,13.22,13.27,13.33,13.40,13.46,13.52,13.58,13.59,13.65,13.71,13.78,13.84,13.90,13.97,13.99,14.04,14.10,14.12,14.14,14.16,14.19,14.24,14.25,14.28,14.33,14.38,14.44,14.47,14.51,14.52,14.56,14.59,14.62,14.64,14.71,14.76,14.81,14.86,14.91,14.95,15.00,15.03,15.05,15.08,15.09,15.16,15.21,15.24,15.27,15.30,15.33,15.37,15.41,15.47,15.52,15.58,15.60,15.62,15.68,15.75,15.76,15.82,15.88,15.90,15.94,15.98,15.99,16.01,16.04,16.10,16.16,16.22,16.25,16.26,16.29,16.32,16.34,16.37,16.38,16.40,16.46,16.52,16.59,16.60,16.66,16.68,16.74,16.78,16.80,16.83,16.89,16.93,16.96,16.98,17.03,17.05,17.08,17.10,17.15,17.16,17.20,17.21,17.22,17.24,17.25,17.27,17.29,17.32,17.33,17.35,17.36,17.37,17.39,17.41,17.43,17.44,17.47,17.49,17.51,17.52,17.53,17.57,17.61,17.66,17.72,17.74,17.77,17.83,17.85,17.89,17.94,17.99,18.03,18.10,18.15,18.20,18.26,18.31,18.34,18.39,18.44,18.46,18.50,18.54,18.61,18.67,18.72,18.78,18.85,18.86,18.88,18.89,18.92,18.98,19.05,19.09,19.14,19.15,19.17,19.21,19.24,19.27,19.29,19.30,19.32,19.37,19.42,19.46,19.48,19.52,19.56,19.61,19.64,19.69,19.75,19.77,19.79,19.81,19.84,19.88,19.91,19.92,19.94,19.96,19.98,20.00,20.02,20.03,20.05,20.11,20.15,20.19,20.24,20.30,20.37,20.38,20.41,20.45,20.46,20.47,20.49,20.52,20.57,20.60,20.62,20.64,20.67,20.69,20.71,20.75,20.79,20.82,20.83,20.85,20.87,20.89,20.90,20.91,20.93,20.94,20.97,20.99,21.00,21.03,21.04,21.06,21.08,21.10,21.14,21.17,21.20,21.22,21.24,21.25,21.26,21.27,21.30,21.35,21.37,21.40,21.44,21.47,21.50,21.55,21.58,21.63,21.69,21.76,21.83,21.89,21.97,22.01,22.03,22.04,22.08,22.10,22.12,22.14,22.15,22.18,22.23,22.26,22.28,22.32,22.35,22.38,22.40,22.42,22.44,22.48,22.50,22.52,22.56,22.57,22.63,22.69,22.76,22.81,22.86,22.91,22.98,23.01,23.03,23.10,23.16,23.21,23.22,23.28,23.30,23.33,23.39,23.43,23.50,23.56,23.62,23.69,23.75,23.80,23.86,23.91,23.97,24.03,24.10,24.11,24.17,24.22,24.26,24.28,24.31,24.33,24.36,24.40,24.42,24.44,24.50,24.54,24.60,24.66,24.73,24.78,24.85,24.89,24.93,24.96,24.98,25.04,25.08,25.11,25.17,25.18,25.19,25.21,25.22,25.23,25.24,25.27,25.29,25.31,25.32,25.33,25.34,25.36,25.37,25.38,25.40,25.42,25.43,25.45,25.47,25.50,25.53,25.55,25.57,25.58,25.59,25.62,25.67,25.68,25.71,25.75,25.79,25.82,25.88,25.93,25.99,26.00,26.04,26.09,26.15,26.18,26.20,26.22,26.24,26.28,26.30,26.32,26.36,26.38,26.40,26.42,26.43,26.44,26.46,26.49,26.50,26.51,26.54,26.58,26.65,26.69,26.74,26.80,26.85,26.89,26.94,26.97,27.01,27.06,27.07,27.08,27.10,27.14,27.18,27.23,27.24,27.27,27.30,27.34,27.35,27.36,27.38,27.40,27.41,27.43,27.44,27.47,27.49,27.51,27.56,27.59,27.60,27.62,27.64,27.67,27.71,27.73,27.75,27.78,27.79,27.82,27.83,27.84,27.89,27.90,27.91,27.96,28.03,28.05,28.06,28.08,28.09,28.13,28.16,28.18,28.24,28.31,28.32,28.37,28.38,28.40,28.42,28.43,28.44,28.48,28.52,28.57,28.61,28.63,28.68,28.73,28.79,28.84,28.86,28.88,28.90,28.92,28.93,28.94,28.97,28.98,29.02,29.04,29.06,29.07,29.09,29.11,29.12,29.13,29.14,29.16,29.17,29.21,29.23,29.25,29.29,29.33,29.36,29.38,29.41,29.45,29.47,29.51,29.53,29.54,29.56,29.57,29.58,29.61,29.64,29.67,29.68,29.71,29.74,29.75,29.77,29.80,29.83,29.84,29.88,29.90,29.95,29.96,29.97,29.99,30.00,30.03,30.05,30.07,30.09,30.12,30.15,30.19,30.21,30.26,30.31,30.33,30.34,30.36,30.37,30.39,30.41,30.44,30.50,30.52,30.53,30.55,30.56,30.57,30.58,30.60,30.62,30.65,30.70,30.71,30.78,30.84,30.90,30.91,30.93,30.95,30.96,30.97,31.01,31.04,31.07,31.08,31.11,31.18,31.24,31.26,31.31,31.35,31.42,31.46,31.48,31.54,31.59,31.63,31.66,31.71,31.76,31.82,31.84,31.85,31.86,31.87,31.90,31.92,31.94,31.98,32.00,32.01,32.03,32.05,32.06,32.07,32.09,32.10,32.13,32.17,32.19,32.20,32.26,32.28,32.30,32.35,32.38,32.44,32.46,32.47,32.48,32.51,32.53,32.55,32.62,32.68,32.70,32.74,32.76,32.80,32.82,32.87,32.91,32.96,33.00,33.01,33.04,33.07,33.09,33.12,33.13,33.17,33.22,33.23,33.26,33.32,33.39,33.44,33.50,33.57,33.62,33.67,33.69,33.70,33.73,33.75,33.77,33.78,33.80,33.81,33.83,33.88,33.94,33.99,34.05,34.11,34.18,34.24,34.31,34.33,34.37,34.42,34.49,34.56,34.62,34.67,34.71,34.72,34.74,34.78,34.81,34.83,34.84,34.87,34.93,34.96,35.02,35.08,35.11,35.17,35.22,35.29,35.31,35.32,35.34,35.35,35.36,35.38,35.40,35.42,35.43,35.48,35.53,35.56,35.58,35.61,35.65,35.67,35.69,35.71,35.72,35.75,35.78,35.80,35.83,35.84,35.85,35.89,35.90,35.93,35.94,35.96,35.98,35.99,36.00,36.01,36.03,36.06,36.07,36.09,36.11,36.13,36.17,36.18,36.22,36.26,36.31,36.33,36.35,36.37,36.39,36.41,36.47,36.50,36.52,36.53,36.55,36.59,36.63,36.65,36.67,36.70,36.72,36.74,36.77,36.80,36.82,36.83,36.86,36.90,36.94,36.99,37.03,37.05,37.07,37.09,37.10,37.14,37.15,37.17,37.22,37.25,37.30,37.31,37.32,37.38,37.40,37.41,37.43,37.47,37.52,37.56,37.61,37.64,37.65,37.66,37.70,37.71,37.74,37.76,37.77,37.81,37.82,37.84,37.86,37.88,37.89,37.92,37.95,37.99,38.00,38.02,38.04,38.05,38.08,38.09,38.11,38.13,38.16,38.18,38.21,38.24,38.28,38.34,38.36,38.38,38.43,38.44,38.46,38.48,38.49,38.50,38.55,38.58,38.63,38.64,38.66,38.70,38.73,38.75,38.80,38.86,38.91,38.92,38.94,38.97,38.99,39.03,39.05,39.07,39.10,39.13,39.15,39.17,39.19,39.20,39.24,39.30,39.34,39.36,39.40,39.42,39.44,39.48,39.52,39.57,39.62,39.65,39.66,39.67,39.70,39.74,39.76,39.80,39.83,39.85,39.87,39.88,39.90,39.92,39.94,39.96,39.98,39.99,40.01,40.03,40.05,40.07,40.09,40.12,40.16,40.17,40.19,40.21,40.22,40.24,40.25,40.26,40.27,40.28,40.29,40.30,40.32,40.34,40.35,40.36,40.38,40.39,40.43,40.45,40.47,40.48,40.53,40.54,40.55,40.57,40.58,40.59,40.61,40.63,40.64,40.67,40.71,40.73,40.75,40.77,40.79,40.81,40.84,40.85,40.87,40.88,40.89,40.93,40.97,41.00,41.01,41.02,41.05,41.08,41.10,41.12,41.14,41.15,41.17,41.18,41.20,41.23,41.28,41.29,41.31,41.33,41.35,41.38,41.42,41.46,41.48,41.49,41.50,41.54,41.55,41.58,41.60,41.63,41.65,41.69,41.75,41.81,41.86,41.90,41.91,41.92,41.93,41.95,41.99,42.02,42.05,42.08,42.10,42.12,42.14,42.18,42.20,42.25,42.29,42.31,42.32,42.35,42.36,42.40,42.42,42.47,42.53,42.57,42.58,42.60,42.61,42.63,42.64,42.65,42.67,42.70,42.71,42.74,42.75,42.77,42.79,42.82,42.83,42.84,42.85,42.87,42.88,42.90,42.91,42.92,42.93,42.94,42.95,42.97,42.99,43.00,43.01,43.02,43.06,43.09,43.12,43.14,43.15,43.18,43.20,43.22,43.23,43.25,43.27,43.29,43.32,43.33,43.34,43.37,43.38,43.40,43.45,43.50,43.53,43.55,43.56,43.58,43.60,43.62,43.65,43.68,43.72,43.74,43.77,43.78,43.81,43.88,43.92,43.96,44.01,44.03,44.04,44.07,44.08,44.11,44.13,44.15,44.18,44.20,44.21,44.23,44.25,44.27,44.28,44.29,44.31,44.33,44.36,44.37,44.40,44.45,44.48,44.52,44.57,44.63,44.67,44.68,44.70,44.73,44.79,44.83,44.85,44.87,44.92,44.94,44.96,44.97,44.99,45.03,45.04,45.07,45.09,45.12,45.13,45.14,45.16,45.17,45.20,45.23,45.24,45.26,45.31,45.36,45.38,45.40,45.43,45.44,45.48,45.50,45.51,45.53,45.54,45.58,45.60,45.61,45.63,45.66,45.71,45.72,45.74,45.77,45.78,45.79,45.81,45.84,45.87,45.89,45.92,45.96,45.98,46.01,46.02,46.03,46.05,46.07,46.09,46.10,46.11,46.13,46.14,46.17,46.19,46.20,46.22,46.24,46.30,46.34,46.38,46.41,46.44,46.50,46.54,46.61,46.65,46.71,46.73,46.78,46.79,46.81,46.83,46.84,46.85,46.88,46.91,46.94,46.96,46.98,46.99,47.01,47.03,47.06,47.07,47.09,47.11,47.12,47.14,47.15,47.17,47.18,47.20,47.21,47.23,47.25,47.28,47.31,47.34,47.35,47.39,47.41,47.43,47.45,47.49,47.51,47.53,47.58,47.62,47.65,47.68,47.72,47.74,47.76,47.77,47.82,47.84,47.85,47.88,47.90,47.93,47.95,47.96,47.97,47.98,48.00,48.03,48.07,48.11,48.12,48.15,48.19,48.20,48.21,48.23,48.24,48.26,48.28,48.31,48.35,48.36,48.39,48.42,48.45,48.46,48.49,48.51,48.56,48.62,48.65,48.66,48.68,48.69,48.70,48.71,48.73,48.75,48.76,48.80,48.81,48.84,48.86,48.88,48.91,48.93,48.95,48.98,49.01,49.03,49.07,49.11,49.13,49.16,49.18,49.22,49.27,49.28,49.30,49.36,49.38,49.39,49.41,49.47,49.50,49.53,49.57,49.58,49.60,49.63,49.64,49.68,49.69,49.70,49.72,49.74,49.76,49.77,49.79,49.83,49.87,49.88,49.90,49.93,49.96,49.99,50.01,50.07,50.08,50.10,50.13,50.14,50.16,50.17,50.18,50.20,50.21,50.23,50.24,50.26,50.27,50.29,50.31,50.33,50.35,50.37,50.39,50.42,50.45,50.48,50.50,50.52,50.53,50.54,50.57,50.60,50.63,50.66,50.68,50.70,50.75,50.77,50.79,50.83,50.89,50.95,50.96,51.00,51.05,51.10,51.14,51.17,51.20,51.22,51.24,51.26,51.31,51.32,51.34,51.38,51.43,51.50,51.51,51.56,51.59,51.61,51.66,51.68,51.74,51.79,51.80,51.81,51.86,51.88,51.91,51.92,51.96,52.00,52.02,52.04,52.06,52.10,52.12,52.13,52.16,52.20,52.21,52.23,52.24,52.26,52.27,52.32,52.34,52.35,52.37,52.40,52.41,52.43,52.45,52.49,52.52,52.54,52.56,52.57,52.58,52.59,52.60,52.62,52.63,52.65,52.67,52.69,52.72,52.74,52.77,52.79,52.81,52.83,52.85,52.87,52.88,52.91,52.93,52.96,52.99,53.00,53.02,53.04,53.07,53.10,53.13,53.16,53.18,53.19,53.22,53.24,53.25,53.27,53.28,53.30,53.33,53.36,53.38,53.40,53.43,53.45,53.47,53.50,53.52,53.58,53.63,53.64,53.66,53.72,53.76,53.79,53.81,53.83,53.84,53.86,53.87,53.90,53.92,53.93,53.94,53.96,53.98,53.99,54.01,54.02,54.03,54.05,54.07,54.10,54.11,54.16,54.20,54.22,54.25,54.29,54.31,54.37,54.40,54.47,54.51,54.55,54.60,54.65,54.70,54.73,54.75,54.76,54.77,54.79,54.80,54.82,54.83,54.85,54.86,54.87,54.89,54.90,54.92,54.94,54.96,54.97,54.98,55.00,55.01,55.03,55.05,55.10,55.13,55.14,55.17,55.23,55.29,55.31,55.34,55.36,55.39,55.41,55.44,55.47,55.49,55.51,55.53,55.55,55.56,55.58,55.59,55.61,55.63,55.65,55.66,55.69,55.70,55.72,55.76,55.78,55.80,55.82,55.83,55.87,55.90,55.93,55.95,55.98,56.00,56.02,56.03,56.04,56.07,56.09,56.12,56.14,56.15,56.18,56.20,56.21,56.23,56.25,56.26,56.29,56.30,56.32,56.33,56.36,56.38,56.41,56.44,56.47,56.48,56.50,56.51,56.52,56.54,56.55,56.57,56.59,56.62,56.63,56.64,56.70,56.73,56.74,56.77,56.78,56.80,56.82,56.84,56.86,56.87,56.90,56.92,56.93,56.94,56.97,56.98,56.99,57.01,57.03,57.04,57.05,57.08,57.10,57.11,57.12,57.14,57.15,57.16,57.17,57.19,57.20,57.22,57.24,57.25,57.27,57.29,57.31,57.33,57.35,57.38,57.39,57.40,57.41,57.44,57.47,57.49,57.50,57.52,57.54,57.56,57.57,57.60,57.62,57.65,57.67,57.70,57.72,57.73,57.77,57.81,57.84,57.88,57.89,57.93,57.95,57.96,58.01,58.02,58.04,58.05,58.06,58.09,58.11,58.12,58.14,58.16,58.17,58.19,58.20,58.21,58.22,58.24,58.26,58.27,58.28,58.30,58.32,58.33,58.35,58.37,58.39,58.41,58.43,58.45,58.46,58.47,58.49,58.52,58.56,58.60,58.61,58.66,58.69,58.73,58.75,58.77,58.78,58.83,58.86,58.87,58.92,58.97,59.00,59.03,59.05,59.06,59.09,59.10,59.11,59.13,59.14,59.15,59.16,59.18,59.20,59.22,59.23,59.24,59.25,59.26,59.27,59.28,59.30,59.31,59.32,59.34,59.35,59.37,59.38,59.40,59.42,59.43,59.44,59.46,59.48,59.50,59.52,59.53,59.54,59.56,59.57,59.59,59.60,59.62,59.63,59.64,59.66,59.67,59.69,59.71,59.72,59.73,59.74,59.76,59.77,59.79,59.80,59.81,59.84,59.85,59.86,59.87,59.90,59.92,59.94,59.95,59.97,60.00,60.01,60.02,60.06,60.08,60.09,60.12,60.15,60.17,60.20,60.22,60.23,60.25,60.26,60.27,60.29,60.31,60.33,60.37,60.39,60.43,60.48,60.52,60.56,60.61,60.65,60.68,60.70,60.72,60.74,60.75,60.77,60.78,60.79,60.83,60.85,60.88,60.90,60.91,60.94,60.96,61.00,61.02,61.06,61.08,61.10,61.13,61.14,61.18,61.21,61.24,61.27,61.28,61.35,61.42,61.44,61.48,61.52,61.54,61.57,61.59,61.63,61.65,61.68,61.69,61.70,61.71,61.73,61.74,61.77,61.79,61.82,61.84,61.86,61.88,61.91,61.94,61.98,61.99,62.01,62.04,62.05,62.07,62.10,62.12,62.18,62.23,62.27,62.29,62.31,62.34,62.37,62.38,62.39,62.41,62.42,62.44,62.46,62.49,62.50,62.54,62.55,62.56,62.59,62.60,62.61,62.63,62.64,62.65,62.67,62.68,62.70,62.72,62.73,62.74,62.77,62.78,62.80,62.82,62.84,62.85,62.87,62.88,62.90,62.92,62.95,62.96,62.97,62.99,63.01,63.02,63.03,63.05,63.06],\r\n\t\t\t\t\tgraphEle           : [435.40,435.40,435.60,435.60,435.80,435.80,435.80,435.80,436.00,436.20,436.00,436.40,436.40,436.40,436.20,436.20,436.20,436.80,436.80,436.60,436.80,436.80,436.80,436.80,436.60,437.20,437.00,436.80,436.60,436.80,436.40,436.40,436.60,436.60,436.80,436.80,437.00,436.60,437.00,436.60,436.80,436.20,436.20,436.20,436.20,436.40,436.40,436.40,436.20,435.80,435.60,435.80,436.20,436.20,436.20,436.20,435.80,435.60,435.80,435.40,435.20,435.00,434.80,434.60,434.20,434.40,434.80,434.80,434.60,434.60,434.40,434.40,434.40,434.60,434.60,434.60,434.40,434.60,434.80,434.60,434.40,434.00,434.00,434.20,434.40,434.40,434.60,434.40,434.60,434.40,434.40,434.40,434.40,434.20,434.20,434.00,433.80,433.80,433.80,434.00,433.40,433.20,433.00,433.00,432.60,432.40,432.20,432.40,432.00,431.20,431.20,431.40,431.60,431.80,431.60,430.80,430.40,429.80,428.80,427.60,426.40,426.40,425.60,425.20,424.00,423.00,421.80,421.00,421.00,421.40,422.00,423.40,424.20,425.00,425.40,426.00,426.40,427.00,427.20,427.80,428.20,428.40,428.80,429.00,429.20,429.40,429.80,429.80,430.00,430.40,430.80,430.80,430.80,430.80,430.80,430.60,430.40,430.60,431.00,430.80,430.40,430.00,429.60,429.00,428.80,427.40,427.40,427.40,427.80,428.40,429.00,429.60,430.00,430.00,430.20,430.00,430.00,429.80,429.80,429.60,429.20,428.80,428.80,428.60,428.60,428.80,428.80,429.00,429.00,428.60,428.80,428.80,428.80,428.80,428.60,428.40,428.40,428.40,428.40,428.60,428.80,428.80,428.60,428.40,428.40,428.20,428.00,428.00,427.60,426.80,425.80,425.60,425.20,424.40,423.40,422.20,421.60,421.40,421.00,420.60,419.80,419.00,418.60,418.60,418.60,418.60,418.60,418.60,417.80,417.80,418.40,418.20,418.20,418.40,418.20,418.40,418.40,417.60,417.60,417.80,417.40,417.20,417.20,417.60,417.80,417.80,418.00,418.20,418.20,418.40,418.60,418.80,419.00,419.00,419.20,419.40,419.40,419.80,420.00,420.80,420.80,421.00,421.40,421.80,422.40,423.00,423.00,423.60,424.20,424.60,424.80,424.80,425.80,425.60,426.00,426.60,426.40,426.20,426.40,426.40,426.40,426.40,426.60,427.20,427.40,427.20,427.40,427.40,427.40,427.60,427.60,427.60,427.60,427.60,427.40,427.20,427.00,427.40,427.20,427.00,427.20,427.00,427.00,426.40,426.60,426.60,426.20,425.80,424.80,424.20,424.20,424.20,424.40,425.80,426.80,427.00,426.80,427.40,427.60,427.60,427.00,426.60,426.20,426.00,426.20,426.00,425.80,425.60,425.60,425.80,426.00,426.60,426.40,426.20,426.00,425.80,425.40,425.60,425.80,426.00,425.80,425.80,425.40,424.80,423.80,423.60,423.20,423.00,422.20,422.00,422.20,422.80,424.00,425.40,425.60,425.60,425.40,425.40,425.20,425.20,425.00,424.80,424.40,424.20,424.20,423.60,423.20,423.20,424.20,424.40,424.40,424.40,424.40,424.40,424.20,424.20,424.00,423.60,423.00,422.60,422.00,421.60,421.40,421.00,420.80,420.20,420.00,419.60,419.20,419.20,419.20,419.00,419.00,418.40,418.40,417.80,417.60,418.00,418.80,418.80,418.80,418.80,418.60,418.60,418.60,417.80,417.40,417.60,418.00,418.60,418.80,418.80,419.00,419.20,419.80,420.00,419.80,419.20,418.00,418.00,418.20,419.20,421.00,420.40,420.00,419.40,419.20,418.20,417.40,417.40,417.40,417.40,417.00,417.20,417.20,417.20,417.40,417.40,418.20,418.60,419.00,419.20,419.80,420.20,420.40,420.40,420.60,420.40,420.40,420.80,421.00,421.20,421.20,421.00,420.80,420.80,420.20,420.00,419.20,419.20,419.20,419.20,419.20,419.00,418.60,418.00,417.00,417.00,417.00,416.60,416.60,416.40,417.20,418.00,418.40,418.80,419.00,419.00,419.20,419.20,419.20,419.20,419.00,419.60,419.60,419.80,420.20,420.60,420.80,421.20,421.60,422.00,422.20,422.20,422.20,422.60,422.80,422.60,423.00,422.80,422.60,422.60,422.80,422.80,422.80,423.00,422.80,423.00,423.00,423.00,423.00,423.20,423.40,423.80,423.80,423.80,423.80,424.20,424.20,424.20,424.20,424.60,424.80,424.80,424.80,425.20,425.20,424.60,424.60,423.80,423.60,423.00,422.60,422.40,422.40,421.80,421.20,420.80,420.20,419.60,419.00,418.60,418.00,417.00,416.80,415.60,415.00,414.00,413.60,413.60,413.80,414.60,415.40,416.00,416.60,417.80,418.80,420.00,421.20,421.80,422.20,422.40,422.60,422.00,421.80,421.60,421.40,421.40,421.20,420.40,420.00,419.60,419.00,419.00,419.20,419.20,420.20,420.40,420.40,420.00,419.00,418.20,418.00,418.20,419.00,419.80,420.20,420.80,420.80,420.60,420.00,419.60,419.60,419.60,419.80,419.60,419.20,419.00,419.40,419.20,419.20,419.00,419.00,418.80,418.60,419.60,419.60,419.60,419.80,419.40,419.00,419.20,419.20,419.00,418.80,418.40,418.60,418.20,418.40,418.20,418.00,417.60,417.80,417.80,416.60,415.40,415.00,414.80,414.60,414.20,413.60,413.40,413.20,412.80,412.20,411.80,411.60,411.80,412.40,412.40,411.80,411.40,412.60,413.20,413.80,414.40,415.20,416.40,416.80,417.40,418.00,418.40,418.80,418.80,419.20,419.40,419.20,419.20,419.20,419.20,419.20,419.60,419.60,419.60,419.40,419.20,418.80,418.20,418.00,417.80,417.40,417.00,416.20,415.00,414.20,412.40,410.60,410.00,409.60,408.80,408.20,408.00,407.40,407.40,407.20,407.20,405.60,405.60,407.40,407.20,407.00,406.80,406.80,406.20,406.40,406.20,406.20,406.00,405.80,406.20,407.20,407.40,407.40,408.00,408.20,407.40,407.80,407.80,407.60,407.40,407.20,407.20,406.40,406.00,405.80,406.00,407.40,407.40,407.40,407.40,407.20,407.20,407.00,407.20,407.40,406.60,406.20,405.80,405.60,405.40,405.20,405.20,405.00,405.00,405.20,405.20,405.20,405.60,405.60,405.40,405.60,405.80,405.60,405.00,404.60,404.60,404.20,404.40,404.60,404.80,405.00,404.60,404.60,404.60,404.60,404.40,403.40,403.40,404.00,404.20,404.40,404.80,403.60,403.40,403.20,402.80,402.80,403.20,403.40,403.40,403.40,404.20,404.00,404.20,404.20,404.20,404.20,404.20,404.20,404.20,404.20,404.40,404.20,404.20,404.00,404.00,403.80,403.80,403.80,403.40,403.40,403.20,402.40,402.40,402.60,402.60,402.60,402.80,402.80,403.00,402.60,402.80,402.00,403.00,403.60,404.00,403.80,403.80,403.60,403.60,403.40,403.40,403.40,403.80,403.80,404.00,404.20,404.40,404.80,405.00,404.80,404.40,404.20,404.20,404.20,404.60,405.00,406.40,407.60,407.80,408.00,408.20,408.40,408.60,408.20,408.40,408.60,408.40,408.00,407.00,406.80,405.80,404.80,403.60,403.40,403.40,403.60,403.40,403.80,404.00,404.20,403.60,403.00,403.20,404.00,403.80,404.00,404.00,403.40,403.20,403.20,403.20,403.40,403.40,403.40,403.20,403.40,403.20,403.40,403.80,403.80,403.40,403.00,402.60,402.60,402.80,402.80,403.40,403.40,403.40,403.60,403.40,403.40,403.40,403.20,403.00,402.60,402.40,402.20,401.80,402.00,402.00,402.00,402.20,402.20,401.80,401.60,401.60,402.00,402.20,402.40,402.60,402.60,402.60,402.80,402.60,402.80,403.00,403.40,403.40,403.60,403.40,403.20,403.00,402.80,402.60,402.60,402.80,403.80,406.20,408.40,409.80,410.40,411.00,411.60,412.00,412.60,412.80,412.60,411.80,410.80,410.20,409.20,408.40,407.00,406.00,405.00,404.60,404.20,402.80,402.80,402.60,402.60,402.20,402.00,402.00,402.00,402.00,401.80,401.60,402.00,402.20,402.20,402.60,402.80,403.60,403.80,404.00,404.40,405.00,405.60,406.00,406.40,406.80,407.00,407.20,407.00,407.00,406.80,406.20,406.00,405.40,405.40,405.00,404.80,404.40,403.80,403.00,402.80,402.40,402.00,401.80,401.80,401.60,401.60,401.60,401.60,401.60,401.60,401.60,401.60,402.00,401.80,402.00,402.20,402.00,401.80,402.20,401.80,401.60,401.40,401.40,400.60,400.80,400.80,401.00,401.40,400.80,400.40,400.00,400.20,399.60,400.40,400.80,400.40,400.20,399.40,398.00,397.80,398.00,398.40,399.60,400.60,400.60,400.20,400.00,399.80,399.60,399.20,398.40,398.40,398.40,399.00,399.20,399.00,399.00,399.40,399.80,399.60,399.60,399.60,399.60,399.60,399.60,399.60,399.60,399.40,399.40,399.40,399.40,399.20,399.20,399.00,399.00,399.00,399.00,398.80,398.60,398.60,398.80,398.80,398.60,398.20,398.60,399.00,399.40,399.80,399.80,399.80,399.80,399.60,399.20,399.00,399.00,399.00,398.40,398.60,399.40,399.60,399.80,399.40,399.20,399.20,399.40,399.40,399.00,399.00,398.60,398.80,399.40,399.40,398.80,398.80,398.80,398.80,399.40,399.20,399.40,399.40,398.60,399.00,399.60,399.80,399.80,399.80,399.80,399.80,399.60,399.00,398.40,398.40,398.20,398.20,398.20,398.60,398.60,398.40,399.00,399.00,399.40,399.40,399.40,399.40,399.60,399.60,399.60,399.80,399.60,399.40,399.60,399.60,399.40,399.20,399.20,399.20,399.40,399.60,399.80,399.80,400.00,400.20,400.00,400.40,400.40,400.60,400.40,400.40,400.40,400.20,399.60,399.60,399.80,400.00,400.20,400.20,400.20,400.20,399.60,399.60,399.40,399.20,399.20,399.40,399.40,399.20,399.40,399.60,400.00,399.60,399.80,399.80,399.80,400.00,400.40,400.40,400.40,400.60,400.60,400.20,400.40,400.60,400.60,400.60,400.80,401.00,400.80,401.20,401.00,401.00,401.00,401.00,401.00,401.20,401.60,401.60,401.80,401.60,401.80,402.20,402.40,402.40,402.40,402.40,402.60,402.60,402.20,402.40,402.80,403.40,403.60,403.80,404.40,404.40,405.20,405.60,405.60,405.80,406.40,406.80,407.00,407.00,407.40,407.60,407.60,406.60,406.00,406.00,405.00,404.00,403.60,403.60,404.80,406.20,405.80,405.20,405.00,404.80,405.00,405.00,405.00,405.00,405.00,405.00,405.40,405.40,405.40,405.40,405.40,405.40,405.20,405.20,405.20,405.40,405.40,405.20,405.60,405.40,405.20,404.60,401.20,401.40,401.60,402.00,402.40,402.60,403.20,403.20,403.40,403.80,403.80,404.20,403.80,403.40,403.20,402.60,402.40,402.20,402.00,402.20,401.60,401.80,401.80,401.80,401.60,401.40,401.40,402.00,402.00,402.00,402.20,402.20,402.60,402.60,403.00,403.40,403.80,404.00,404.20,404.40,404.40,404.80,405.40,405.40,405.60,406.00,406.60,406.60,406.60,406.80,406.60,406.60,407.00,407.60,407.60,408.40,408.00,408.20,408.00,408.00,408.20,408.20,408.40,408.40,408.40,408.40,408.60,408.80,409.60,410.40,409.60,410.60,411.00,411.40,411.80,412.00,411.80,412.00,412.00,412.00,412.20,412.20,411.80,411.40,411.00,411.00,411.00,410.80,410.80,410.60,411.00,411.20,411.20,411.20,411.20,411.40,411.80,411.60,411.40,411.40,411.60,411.60,411.40,411.40,411.80,411.80,411.80,411.80,411.60,411.60,411.20,411.20,411.00,411.00,411.00,411.20,411.20,411.20,411.20,411.60,411.80,411.60,410.60,410.00,409.40,409.20,408.60,408.20,408.20,408.20,408.20,408.80,409.20,410.20,411.20,411.80,412.20,412.60,413.40,413.20,412.80,412.60,412.40,411.80,411.20,410.40,409.80,409.60,410.00,409.80,410.00,410.00,409.60,409.60,409.60,409.40,408.80,408.80,408.80,408.40,407.60,407.40,406.80,406.00,406.00,406.00,406.40,406.60,406.20,406.20,405.40,405.60,405.40,405.40,405.60,406.00,406.60,407.00,407.40,407.80,408.80,409.00,409.00,409.00,408.80,408.40,408.40,408.00,407.60,407.20,406.80,406.20,405.80,405.40,405.20,404.00,403.80,403.40,403.20,403.80,404.40,405.00,405.20,406.00,406.20,406.40,406.80,406.80,407.20,407.20,407.00,406.80,406.20,406.00,406.00,405.60,405.40,405.00,404.40,404.20,404.20,404.00,403.80,403.00,403.00,403.00,403.20,404.20,404.60,405.20,405.20,405.40,405.40,405.40,405.60,405.60,405.20,404.60,404.40,404.20,404.20,403.40,403.80,404.00,404.20,404.40,404.00,403.60,403.00,402.60,402.40,402.40,402.40,402.40,402.00,401.40,401.40,401.40,401.80,402.80,403.00,403.20,403.60,403.80,404.40,404.60,404.80,404.80,404.60,403.80,403.60,403.40,403.00,403.00,403.20,403.40,403.60,403.60,403.60,403.80,403.60,403.40,403.40,403.20,402.80,402.80,402.80,402.80,402.60,402.60,402.60,402.20,401.80,401.60,401.20,400.80,400.60,400.60,400.40,400.00,399.80,399.80,399.40,399.00,398.80,398.80,398.40,397.40,396.80,395.40,394.20,393.80,393.80,394.20,394.00,393.60,393.00,393.00,393.00,393.00,393.00,394.20,395.00,395.40,395.80,395.80,396.60,397.00,397.40,398.40,398.00,397.20,397.00,396.40,395.40,394.80,394.40,394.60,395.40,395.80,396.20,396.40,396.20,396.40,397.20,399.20,400.80,402.20,402.40,402.40,402.40,401.80,401.60,401.40,401.80,402.80,403.00,403.00,402.80,402.60,402.60,402.20,402.00,401.80,401.20,400.40,401.20,401.80,402.00,402.20,402.40,402.60,402.80,402.80,402.60,403.00,402.80,402.80,403.00,402.80,402.80,402.60,402.00,401.80,401.20,400.60,400.20,399.60,398.80,398.40,397.80,397.40,396.60,395.40,394.60,393.80,393.40,393.20,392.80,392.80,392.80,392.60,393.00,393.20,393.20,393.80,394.20,394.60,395.20,396.00,396.60,397.00,398.00,399.20,400.20,401.40,402.40,403.40,404.60,405.40,406.00,406.60,406.80,407.00,406.80,406.80,406.60,406.60,406.20,406.40,406.40,406.20,405.80,405.80,405.60,405.20,404.60,404.60,404.80,405.40,405.60,406.00,406.20,406.40,406.20,406.00,405.60,405.20,404.60,404.00,403.40,402.20,401.00,399.40,398.60,398.20,398.00,397.80,397.00,396.20,395.40,395.60,395.60,395.60,395.80,396.20,397.20,398.00,398.00,397.60,397.40,397.40,397.40,397.40,397.20,397.60,398.00,399.20,399.60,400.40,401.40,402.20,403.20,403.60,404.00,404.60,405.00,405.60,406.60,407.40,408.60,408.80,409.20,409.40,409.80,410.00,409.80,410.20,410.60,410.80,411.00,410.80,410.20,409.80,409.60,408.60,407.80,408.40,410.00,410.40,410.40,410.60,411.00,411.40,411.40,411.40,410.80,410.60,410.60,410.40,410.40,410.40,411.00,411.00,411.00,411.40,411.20,411.00,411.20,411.00,410.60,410.40,410.00,409.40,408.80,408.60,408.60,408.00,406.40,405.40,404.60,404.20,403.60,403.00,401.60,400.40,399.60,399.40,399.00,398.80,398.40,398.00,398.20,398.60,398.80,399.40,400.00,399.60,399.60,399.60,399.80,400.40,401.60,402.80,403.80,405.00,406.20,407.40,408.60,409.40,411.00,412.00,412.80,412.80,413.80,414.40,415.20,416.00,416.20,416.80,417.40,417.40,417.60,417.60,417.40,417.60,417.20,416.80,416.60,416.20,416.00,415.60,415.20,415.00,414.00,413.60,412.80,412.40,412.00,411.60,411.20,410.80,409.60,409.00,409.00,409.20,409.20,409.80,410.40,411.40,412.20,412.60,413.40,413.80,414.60,415.40,416.00,416.80,417.60,419.00,420.20,421.40,422.60,423.40,423.80,424.20,424.20,424.00,423.20,422.20,421.20,420.00,419.00,418.20,416.60,415.60,415.00,414.80,414.80,414.80,415.20,415.20,415.40,415.60,416.20,416.80,417.60,418.80,419.80,421.00,422.00,423.00,424.20,425.20,426.40,427.40,427.40,426.80,426.00,425.00,424.20,423.80,422.20,421.60,420.40,420.60,420.60,420.40,420.00,419.60,419.00,419.20,419.20,419.20,418.80,418.80,417.80,417.20,417.40,417.80,417.40,417.20,417.00,416.60,416.60,416.20,415.80,415.80,415.40,415.20,415.20,416.20,416.40,416.60,417.00,417.60,418.80,419.80,420.80,422.00,423.00,424.20,424.60,425.40,426.20,427.40,428.40,429.60,430.40,431.00,432.00,432.80,433.40,434.20,434.80,435.40,436.40,437.00,437.60,438.00,438.60,439.40,439.80,440.20,440.60,440.80,441.00,440.80,441.20,440.80,440.60,440.40,439.80,439.20,439.00,438.80,437.60,437.00,437.00,437.20,437.20,437.20,437.40,437.20,436.80,436.40,436.00,434.00,433.60,433.60,434.40,435.00,435.20,434.40,434.40,433.60,433.20,432.20,431.60,431.40,432.40,434.00,436.00,436.60,436.60,436.80,437.00,438.40,439.00,439.80,440.60,441.60,442.80,443.40,443.80,444.40,445.20,445.00,445.00,444.60,444.40,444.40,444.40,444.00,443.80,443.60,443.40,443.40,443.40,442.60,442.60,443.60,443.80,443.80,444.60,445.80,446.40,447.60,447.60,446.80,445.40,445.20,445.00,444.20,443.40,442.20,442.20,440.60,439.40,438.20,437.40,436.00,435.40,435.00,435.00,434.20,433.20,431.00,430.00,429.20,429.00,428.00,426.60,426.40,426.00,425.20,424.20,423.40,422.60,421.40,421.20,420.80,420.20,419.00,417.60,416.40,416.20,414.80,414.40,413.60,412.40,411.20,411.00,409.60,408.60,408.40,408.20,409.60,410.80,412.00,413.00,413.80,414.40,415.40,416.20,417.20,418.20,418.80,419.40,420.00,421.20,421.80,422.20,423.00,423.60,424.60,425.20,425.80,426.80,427.40,427.80,428.40,428.80,429.40,430.40,431.20,432.20,432.80,433.60,434.60,435.80,436.80,437.60,438.00,438.80,439.40,440.00,440.60,441.40,442.40,442.80,443.80,444.60,445.40,447.00,447.40,448.00,449.00,449.60,450.00,451.00,451.80,452.60,452.80,453.20,453.60,453.60,453.80,454.20,454.60,455.00,455.80,456.00,456.20,456.20,456.80,457.20,457.80,458.00,458.20,458.60,458.80,458.80,458.80,458.80,458.80,458.80,458.80,458.80,458.80,458.60,457.80,456.80,456.20,455.80,454.20,453.20,452.00,451.00,450.60,449.20,448.40,447.20,446.40,446.40,446.20,445.80,445.00,444.60,443.40,443.20,443.00,442.20,442.00,441.20,441.00,440.60,439.40,438.60,437.60,437.00,435.60,434.20,432.80,431.80,430.80,430.40,430.20,430.40,430.40,430.20,430.40,429.60,429.60,429.20,428.80,428.00,427.40,426.60,426.00,425.40,424.40,423.20,422.40,419.80,419.60,418.40,416.60,415.40,413.60,412.20,410.60,408.80,407.60,407.20,406.20,405.40,405.20,404.40,404.20,403.40,403.00,401.80,401.00,400.00,399.60,399.40,398.60,398.20,397.60,397.00,396.20,395.40,394.20,393.60,393.00,392.40,391.80,391.60,390.80,390.80,390.80,391.00,390.80,390.40,390.00,390.00,389.80,389.40,389.20,388.80,388.80,388.80,388.80,388.60,388.40,388.00,387.60,387.40,387.40,387.20,387.40,387.00,387.00,387.00,387.20,387.40],\r\n\t\t\t\t\tgraphSpeed         : [],\r\n\t\t\t\t\tgraphHr            : [],\r\n\t\t\t\t\tgraphAtemp         : [],\r\n\t\t\t\t\tgraphCad           : [],\r\n\t\t\t\t\tgraphGrade         : [],\r\n\t\t\t\t\twaypoints          : [],\r\n\t\t\t\t\tunit               : \"2\",\r\n\t\t\t\t\tunitspeed          : \"0\",\r\n\t\t\t\t\tcolor1             : [\"#3366cc\"],\r\n\t\t\t\t\tcolor2             : \"#3366cc\",\r\n\t\t\t\t\tcolor3             : \"#ff0000\",\r\n\t\t\t\t\tcolor4             : \"#ff77bd\",\r\n\t\t\t\t\tcolor5             : \"#beecff\",\r\n\t\t\t\t\tcolor6             : \"#beecff\",\r\n\t\t\t\t\tcolor7             : \"#ff77bd\",\r\n\t\t\t\t\tchartFrom1         : \"\",\r\n\t\t\t\t\tchartTo1           : \"\",\r\n\t\t\t\t\tchartFrom2         : \"\",\r\n\t\t\t\t\tchartTo2           : \"\",\r\n\t\t\t\t\tstartIcon          : \"\",\r\n\t\t\t\t\tendIcon            : \"\",\r\n\t\t\t\t\tcurrentIcon        : \"\",\r\n\t\t\t\t\twaypointIcon       : \"\",\r\n\t\t\t\t\tcurrentpositioncon : \"\",\r\n\t\t\t\t\tusegpsposition     : \"\",\r\n\t\t\t\t\tzoomOnScrollWheel  : \"\",\r\n\t\t\t\t\tngGalleries        : [],\r\n\t\t\t\t\tngImages           : [],\r\n\t\t\t\t\tpluginUrl          : \"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\",\r\n\t\t\t\t\tTFApiKey           : \"\",\r\n\t\t\t\t\tMapBoxApiKey           : \"\",\r\n\t\t\t\t\tlangs              : {\r\n\t\t\t\t\t\taltitude        : \"H\u00f6he\",\r\n\t\t\t\t\t\tcurrentPosition : \"Aktuelle Position\",\r\n\t\t\t\t\t\tspeed           : \"Geschwindigkeit\",\r\n\t\t\t\t\t\tgrade           : \"Steigung\",\r\n\t\t\t\t\t\theartRate       : \"Herzfrequenz\",\r\n\t\t\t\t\t\tatemp           : \"Temperatur\",\r\n\t\t\t\t\t\tcadence         : \"Trittfrequenz\",\r\n\t\t\t\t\t\tgoFullScreen    : \"Vollbildansicht\",\r\n\t\t\t\t\t\texitFullFcreen  : \"Vollbild verlassen\",\r\n\t\t\t\t\t\thideImages      : \"Bilder verbergen\",\r\n\t\t\t\t\t\tshowImages      : \"Bilder zeigen\",\r\n\t\t\t\t\t\tbackToCenter\t: \"Zur\u00fcck zur Mitte\"\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\r\n\t\t\t});\r\n\r\n\t\t<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Das Fr\u00fchst\u00fcck im Sleepy Sleepy Hotel wurde im knallgr\u00fcnen Fr\u00fchst\u00fcckssaal serviert. Es war nicht viel los, was wahrscheinlich am Aufpreis von 14\u20ac pro Person lag. Es\u00a0war nicht \u00fcppig, aber von allem was da und wir waren zufrieden. Die Wetterprognose war ziemlich schlecht und die Wege, die als Donauradweg ausgezeichnet sind, versprachen wieder Staub, Schmutz und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[165,312,307,313],"class_list":["post-6441","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-bayern","tag-dillingen","tag-donau","tag-neuburg"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts\/6441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/comments?post=6441"}],"version-history":[{"count":0,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts\/6441\/revisions"}],"wp:attachment":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/media?parent=6441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/categories?post=6441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/tags?post=6441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}