

{"id":5722,"date":"2024-04-06T21:47:39","date_gmt":"2024-04-06T19:47:39","guid":{"rendered":"https:\/\/gothein.de\/reiseblog\/?p=5722"},"modified":"2024-04-19T12:41:02","modified_gmt":"2024-04-19T10:41:02","slug":"rund-um-coimbra","status":"publish","type":"post","link":"https:\/\/gothein.de\/reiseblog\/2024\/04\/06\/rund-um-coimbra\/","title":{"rendered":"Rund um Coimbra"},"content":{"rendered":"\n<p>Um auch in die, durch \u00f6ffentlichen Nahverkehr weniger gut erschlossene Gebiete zu kommen, haben wir uns heute ein Auto gemietet, was wir in ein paar Tagen wieder in Lissabon abgeben sollen. Leider ist es heute wieder ziemlich bew\u00f6lkt und es regnet immer wieder ein paar Tropfen. Der Autovermieter stellt bereits erste braune Tropfen auf dem Auto fest und meinte, eben w\u00e4re es noch sauber gewesen. Das ist der Sahara Staub und der ist hier wirklich rot. Sofort sichtbar auf Jacke, Rucksack und eben unserem Hyundai Kuai. Nach kurzer Zeit ist unser neuer Wagen v\u00f6llig verdreckt. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-1024x1024.jpg\" alt=\"\" class=\"wp-image-5720\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-1536x1536.jpg 1536w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452-60x60.jpg 60w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0938157339821474714005452.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Zun\u00e4chst steuern wir die Kleinstadt Penacova an, mit gro\u00dfartigem Blick \u00fcber das Tal des Mondego, der sp\u00e4ter durch Coimbra fliesst. Google steuert uns \u00fcber eine gr\u00f6\u00dfere Nationalstra\u00dfe und deshalb sind wir schnell da. <\/p>\n\n\n\n<p>Das Kloster \u201eMosteiro de Lorv\u00e3o\u201c \u00fcber winzige Str\u00e4\u00dfchen zu finden ist dann schon etwas schwieriger. Im 19. Jahrhundert enteignet, bewohnt bis die letzte Nonne gestorben war und jetzt wieder mit EU Geldern sukzessive renoviert ist es wieder in einem guten Zustand aber es wird immer weiter restauriert.<\/p>\n\n\n\n<p>Auf dem H\u00fcgel bei einem kleinen D\u00f6rfchen gibt es ausgediente Windm\u00fchlen zu sehen (Moinhos de Gavinhos). Ein Generator erzeugt Strom, f\u00fcr was ist unklar, denn da oben ist nur eine kleines Freizeitgel\u00e4nde. In der Ferne drehen sich die modernen Varianten der Windr\u00e4der. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-1024x1024.jpg\" alt=\"\" class=\"wp-image-5721\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-1536x1536.jpg 1536w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329-60x60.jpg 60w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_093244864476968900804329.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00dcber super steile kleine Wege kommen wir wieder zur N235, die ebenfalls \u00fcber viele Kurven nach Luso f\u00fchrt. Da kommt das Wasser her, was man \u00fcberall in Plastikflaschen findet, es gibt ein, mit EU Geld restauriertes Thermalbad, aber sonst ist der Ort nicht sehr interessant. Wir suchen den Mata Nacional do Bussaco. Google leitet uns \u00fcber  eine winzige Anwohnerstra\u00dfe, die deutlich \u00fcber 30% Steigung hat und l\u00e4sst uns dann entlang zwei Serpentinen auf der Fahrstra\u00dfe laufen, bis wir einen Eingang des Parks finden. <\/p>\n\n\n\n<p>Der Park hat einen alten faszinierenden Baumbestand, uns begr\u00fc\u00dfen einige Korkeichen. F\u00fcr Fu\u00dfg\u00e4nger ist der Eintritt frei und wir folgen einer Komoot Wanderung, die an allen Quellen, Treppen, Kreuzwegstationen und nat\u00fcrlich der gr\u00f6\u00dften Attraktion, dem Bussaco Palast, vorbei f\u00fchrt. Der Palast wird seit Abschaffung der Monarchie als Hotel genutzt. Vom letzten K\u00f6nig Karl I wurde er f\u00fcr seine Gattin errichtet. Etwa 10 Kilometer lang durchqueren wir das Gel\u00e4nde und finden den R\u00fcckweg dann diesmal direkt zu unserem Parkplatz. Das Wetter h\u00e4lt und das steile Gel\u00e4nde ist ein tolles Wandergel\u00e4nde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-1024x1024.jpg\" alt=\"\" class=\"wp-image-5719\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-1536x1536.jpg 1536w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184-60x60.jpg 60w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2024\/04\/20240407_0929457438529229622806184.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Es ist nun schon sp\u00e4ter Nachmittag aber wir entschlie\u00dfen uns dennoch bis hoch zum Stausee des Mondego zu fahren und von der riesigen Betonmauer dann abw\u00e4rts zun\u00e4chst der N2 entlang des Mondego zu folgen. Die N2 ist eine der \u201eNationalstra\u00dfen, die durch das ganze Land f\u00fchren. Wir k\u00f6nnten ihr bis nach Faro folgen. Wir bleiben aber beim Fluss und wir folgen dann der kurvigen N110 mit vielen Blicken \u00fcber das enge Flusstal bis nach Coimbra.<\/p>\n\n\n\n<p>Nach etwas Recherche finden wir heute wieder ein urspr\u00fcngliches portugiesisches Restaurant mit einfacher Einrichtung einer langen gedeckten Tafel f\u00fcr offensichtlich eine etwas gr\u00f6\u00dfere Gesellschaft. Und einen freien Tisch f\u00fcr zwei, an den wir sofort gesetzt werden. Englisch wird hier eher nicht gesprochen und wir bekommen mal wieder von feinstem Fisch und guten Wein.<\/p>\n\n\n\n<p>Insgesamt waren wir ca. 140 km unterwegs und davon gut 10 km zu Fu\u00df. <\/p>\n\n\n<link rel='stylesheet' id='osm-ol3-css-css' href='https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/OL\/10.9.0\/ol.css?ver=6.8.5' type='text\/css' media='all' \/>\n<link rel='stylesheet' id='osm-ol3-ext-css-css' href='https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/css\/osm_map_v3.css?ver=6.8.5' type='text\/css' media='all' \/>\n<link rel='stylesheet' id='osm-map-css-css' href='https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/css\/osm_map.css?ver=6.8.5' type='text\/css' media='all' \/>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-includes\/js\/dist\/vendor\/wp-polyfill.min.js?ver=3.15.0\" id=\"wp-polyfill-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/OL\/10.9.0\/ol.js?ver=10.9.0\" id=\"osm-ol3-library-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/osm-v3-plugin-lib.js?ver=1.0.0\" id=\"osm-ol3-ext-library-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/osm-metabox-events.js?ver=1.0.0\" id=\"osm-ol3-metabox-events-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-includes\/js\/jquery\/jquery.min.js?ver=3.7.1\" id=\"jquery-core-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-includes\/js\/jquery\/jquery-migrate.min.js?ver=3.4.1\" id=\"jquery-migrate-js\"><\/script>\n<script type=\"text\/javascript\" id=\"osm-map-startup-js-extra\">\n\/* <![CDATA[ *\/\nvar translations = {\"openlayer\":\"open layer\",\"openlayerAtStartup\":\"open layer at startup\",\"generateLink\":\"link to this map with opened layers\",\"shortDescription\":\"short description\",\"generatedShortCode\":\"to get a text control link paste this code in your wordpress editor\",\"closeLayer\":\"close layer\",\"cantGenerateLink\":\"put this string in the existing map short code to control this map\"};\n\/* ]]> *\/\n<\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/osm-startup-lib.js?ver=V6.2.5\" id=\"osm-map-startup-js\"><\/script>\n\n        <div id=\"map_ol3js_1\"\n       class=\"osm-map-container undefined\"\n             data-map_name=\"undefined\"\n             data-map=\"map_ol3js_1\"\n             data-autoshow=\"no\"\n             style=\"width:100%;\n                    max-width:100%;\n                    height:450px;\n                    display:block;\n                    overflow:hidden;\n                    border:2px solid grey;\n                    position: relative;\">\n          <div id=\"map_ol3js_1_popup\" class=\"ol-popup\">\n            <a href=\"#\" id=\"map_ol3js_1_popup-closer\" class=\"ol-popup-closer\"><\/a>\n            <div id=\"map_ol3js_1_popup-content\"><\/div>\n          <\/div>\n        <\/div>\n    <script type=\"text\/javascript\">\n\t\t\t  vectorM['map_ol3js_1'] = [];\n\t        \n        var raster = getTileLayer(\"osm\",\"NoKey\");\t\t\t\n\n\t\t\t  var map_ol3js_1 = new ol.Map({\n\t\t\t\tinteractions: ol.interaction.defaults.defaults({mouseWheelZoom:false}),\n\t\t\t\tlayers: [raster],\n\t\t\t\ttarget: \"map_ol3js_1\",\n\t\t\t\tview: new ol.View({\n\t\t\t\t  center: ol.proj.transform([-8.312387,40.293471], \"EPSG:4326\", \"EPSG:3857\"),\n\t\t\t\t  zoom: 10.393476\n\t\t\t\t})\n\t\t\t  });\n\t\t\t  \n    var style_map_ol3js_1_0 = {\n      \"Point\": [new ol.style.Style({\n\n          image: new ol.style.Icon({\n            anchor: [0.5, 41],\n            anchorXUnits: \"fraction\",\n            anchorYUnits: \"pixels\",\n            opacity: 0.75,\n            src: \"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/icons\/mic_blue_pinother_02.png\"\n          })\n      })],\n\n      \"LineString\": [new ol.style.Style({\n        stroke: new ol.style.Stroke({\n          color: \"blue\",\n          width: 8\n        })\n      })],\n      \"MultiLineString\": [new ol.style.Style({\n        stroke: new ol.style.Stroke({\n          color: \"blue\",\n          width: 4\n        })\n      })]\n    };\n\t\t  var vectorL0 = new ol.layer.Vector({\n\t\t\t\tsource: new ol.source.Vector({\n\t\t\t\turl:\"\/reiseblog\/wp-content\/uploads\/gpx\/20240406_Coimbra_Ausflug.gpx\",\n\t\t\t\tformat: new ol.format.GPX({\n\t\t\t\t\textractStyles: false\n\t\t\t\t})\n\t\t\t}),\n\t\t\tzIndex: 92,\n\t\t\tstyle: function(feature, resolution) {return style_map_ol3js_1_0[feature.getGeometry().getType()];}\n\t\t  });\n\t\t  map_ol3js_1.addLayer(vectorL0);addControls2Map(map_ol3js_1,0,0,3,1,5,6,7,0,1);\nosm_addPopupClickhandler(map_ol3js_1,  \"map_ol3js_1\"); \nosm_addMouseHover(map_ol3js_1); <\/script>\n","protected":false},"excerpt":{"rendered":"<p>Um auch in die, durch \u00f6ffentlichen Nahverkehr weniger gut erschlossene Gebiete zu kommen, haben wir uns heute ein Auto gemietet, was wir in ein paar Tagen wieder in Lissabon abgeben sollen. Leider ist es heute wieder ziemlich bew\u00f6lkt und es regnet immer wieder ein paar Tropfen. Der Autovermieter stellt bereits erste braune Tropfen auf dem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[263,264,261],"class_list":["post-5722","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-coimbra","tag-luso","tag-portugal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts\/5722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/comments?post=5722"}],"version-history":[{"count":0,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts\/5722\/revisions"}],"wp:attachment":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/media?parent=5722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/categories?post=5722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/tags?post=5722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}