

{"id":1741,"date":"2017-10-27T19:46:33","date_gmt":"2017-10-28T02:46:33","guid":{"rendered":"http:\/\/gothein.de\/reiseblog\/?p=1741"},"modified":"2017-10-27T20:13:27","modified_gmt":"2017-10-28T03:13:27","slug":"von-huntington-beach-nach-cardiff-by-the-sea","status":"publish","type":"post","link":"https:\/\/gothein.de\/reiseblog\/2017\/10\/27\/von-huntington-beach-nach-cardiff-by-the-sea\/","title":{"rendered":"Von Huntington Beach nach Cardiff by the Sea"},"content":{"rendered":"<p>In der Nacht hat es deutlich abgek\u00fchlt, so dass es sich in meinem Schlafraum gut aushalten lie\u00df. Auch der n\u00e4chste Tag ist sch\u00f6n, aber nicht mehr ganz so hei\u00df angesagt. Ich nehme ein Fr\u00fchst\u00fcck im Starbucks im nahe gelegenen Einkaufszentrum. An der K\u00fcste werde ich dann auf einmal von starkem Nebel \u00fcberrascht. <\/p>\n<p><a href=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421.jpg\" alt=\"\" class=\"wp-image-1740 alignnone size-full\" width=\"1600\" height=\"1600\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421.jpg 1600w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191554-1600x16001713888421-60x60.jpg 60w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p>Ich komme an traumhaften Ferienorten wie Laguna Beach (im Nebel mit eigenartiger Stimmung) oder Dana Point vorbei. Hier lande ich aus Versehen auf einer sehr verkehrsreichen Stra\u00dfe, finde  aber die Radwege bald wieder. Alles ist sehr bev\u00f6lkert bis San Clemente. Teilweise wird man durch Wohngebiete umgeleitet. Das ist zwar ganz nett anzusehen, w\u00e4hrend aber die gro\u00dfe Stra\u00dfe ziemlich gerade durch geht, sind hier viele kleine Kurven, H\u00fcgel und Stop &#8211; Zeichen. Es sammeln sich dadurch doch eine ganze Menge H\u00f6henmeter an. Weiter geht es von San Clemente \u00fcber Radwege, entlang eines endlosen State Parks, den ich fast f\u00fcr mich alleine habe. Dann auf einmal durch Milit\u00e4rgel\u00e4nde, nur f\u00fcr Fahrr\u00e4der erlaubt, mit entsprechenden Warnungen wie &#8222;do not stop&#8220;. Auch da bin ich ganz alleine. Und w\u00e4hrend ich noch so denke, wie super die Radwege hier gef\u00fchrt sind, ist der Spa\u00df auch schon zu Ende. Milit\u00e4rlaster, Bewaffnete und nur noch eine Sandpiste. D.h. es geht auf den Freeway, mit der Nummer 5. Vier Spuren auf jeder Seite, Dimension A5 s\u00fcdlich Frankfurter Kreuz.<\/p>\n<p><a href=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607.jpg\" alt=\"\" class=\"wp-image-1739 alignnone size-full\" width=\"1600\" height=\"1600\" srcset=\"https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607.jpg 1600w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607-150x150.jpg 150w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607-300x300.jpg 300w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607-768x768.jpg 768w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607-1024x1024.jpg 1024w, https:\/\/gothein.de\/reiseblog\/wp-content\/uploads\/2017\/10\/20171027_191723-1600x1600859186607-60x60.jpg 60w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p>Bei Oceanside hat dann diese Episode auch ihr Ende und man wird wieder entlang der K\u00fcste gef\u00fchrt. Oceanside mit Hafen und Pier, Carlsbad sind traumhafte Orte. Man m\u00f6chte \u00fcberall anhalten. Ich entscheide mich dann doch f\u00fcr den vorgeschlagenen Campground San Elijo State Beach vor dem viele Surfer im Wasser d\u00fcmpeln und der einen Kiosk mit Blick auf den Sonnenuntergang hat. Der f\u00e4llt allerdings dem K\u00fcstennebel zum Opfer. Es ist der letzte \u00f6ffentliche Park vor San Diego. Es werden 109 km, 690 H\u00f6henmeter. Der Platz hat links und rechts von der Strasse Camppl\u00e4tze. Vorne die K\u00fcste, hinten die vierspurige Stra\u00dfe und die Eisenbahnlinie, die mangels sicherer \u00dcberg\u00e4nge einen wahnsinnigen L\u00e4rm veranstaltet. Die Hiker &amp; Biker Pl\u00e4tze sind&nbsp; &#8230;<\/p>\n<p>Gerade gehe ich los um die preiswerte Pizzeria auf der anderen Bahnseite mit vielen Bier vom Fass zu besuchen, da kommen Gianna und Kevin bei letzter D\u00e4mmerung angefahren.<\/p>\n<p>Die Pizzeria hat WiFi, Strom an der Bar und da l\u00e4sst es sich gem\u00fctlich sitzen, die M\u00e4dels neben mir haben auch schon gefragt, was ich das so treibe.<\/p>\n<link rel='stylesheet' id='osm-ol3-css-css' href='https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/OL\/10.9.0\/ol.css?ver=6.8.5' type='text\/css' media='all' \/>\n<link rel='stylesheet' id='osm-ol3-ext-css-css' href='https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/css\/osm_map_v3.css?ver=6.8.5' type='text\/css' media='all' \/>\n<link rel='stylesheet' id='osm-map-css-css' href='https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/css\/osm_map.css?ver=6.8.5' type='text\/css' media='all' \/>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-includes\/js\/dist\/vendor\/wp-polyfill.min.js?ver=3.15.0\" id=\"wp-polyfill-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/OL\/10.9.0\/ol.js?ver=10.9.0\" id=\"osm-ol3-library-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/osm-v3-plugin-lib.js?ver=1.0.0\" id=\"osm-ol3-ext-library-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/osm-metabox-events.js?ver=1.0.0\" id=\"osm-ol3-metabox-events-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-includes\/js\/jquery\/jquery.min.js?ver=3.7.1\" id=\"jquery-core-js\"><\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-includes\/js\/jquery\/jquery-migrate.min.js?ver=3.4.1\" id=\"jquery-migrate-js\"><\/script>\n<script type=\"text\/javascript\" id=\"osm-map-startup-js-extra\">\n\/* <![CDATA[ *\/\nvar translations = {\"openlayer\":\"open layer\",\"openlayerAtStartup\":\"open layer at startup\",\"generateLink\":\"link to this map with opened layers\",\"shortDescription\":\"short description\",\"generatedShortCode\":\"to get a text control link paste this code in your wordpress editor\",\"closeLayer\":\"close layer\",\"cantGenerateLink\":\"put this string in the existing map short code to control this map\"};\n\/* ]]> *\/\n<\/script>\n<script type=\"text\/javascript\" src=\"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/js\/osm-startup-lib.js?ver=V6.2.5\" id=\"osm-map-startup-js\"><\/script>\n\n        <div id=\"map_ol3js_1\"\n       class=\"osm-map-container undefined\"\n             data-map_name=\"undefined\"\n             data-map=\"map_ol3js_1\"\n             data-autoshow=\"no\"\n             style=\"width:100%;\n                    max-width:100%;\n                    height:450px;\n                    display:block;\n                    overflow:hidden;\n                    border:2px solid grey;\n                    position: relative;\">\n          <div id=\"map_ol3js_1_popup\" class=\"ol-popup\">\n            <a href=\"#\" id=\"map_ol3js_1_popup-closer\" class=\"ol-popup-closer\"><\/a>\n            <div id=\"map_ol3js_1_popup-content\"><\/div>\n          <\/div>\n        <\/div>\n    <script type=\"text\/javascript\">\n\t\t\t  vectorM['map_ol3js_1'] = [];\n\t        \n        var raster = getTileLayer(\"osm\",\"NoKey\");\t\t\t\n\n\t\t\t  var map_ol3js_1 = new ol.Map({\n\t\t\t\tinteractions: ol.interaction.defaults.defaults({mouseWheelZoom:false}),\n\t\t\t\tlayers: [raster],\n\t\t\t\ttarget: \"map_ol3js_1\",\n\t\t\t\tview: new ol.View({\n\t\t\t\t  center: ol.proj.transform([-117.796,33.292], \"EPSG:4326\", \"EPSG:3857\"),\n\t\t\t\t  zoom: 9\n\t\t\t\t})\n\t\t\t  });\n\t\t\t  \n    var style_map_ol3js_1_0 = {\n      \"Point\": [new ol.style.Style({\n\n          image: new ol.style.Icon({\n            anchor: [0.5, 41],\n            anchorXUnits: \"fraction\",\n            anchorYUnits: \"pixels\",\n            opacity: 0.75,\n            src: \"https:\/\/gothein.de\/reiseblog\/wp-content\/plugins\/osm\/icons\/mic_blue_pinother_02.png\"\n          })\n      })],\n\n      \"LineString\": [new ol.style.Style({\n        stroke: new ol.style.Stroke({\n          color: \"blue\",\n          width: 8\n        })\n      })],\n      \"MultiLineString\": [new ol.style.Style({\n        stroke: new ol.style.Stroke({\n          color: \"blue\",\n          width: 4\n        })\n      })]\n    };\n\t\t  var vectorL0 = new ol.layer.Vector({\n\t\t\t\tsource: new ol.source.Vector({\n\t\t\t\turl:\"\/reiseblog\/wp-content\/uploads\/gpx\/20171027_Huntington.gpx\",\n\t\t\t\tformat: new ol.format.GPX({\n\t\t\t\t\textractStyles: false\n\t\t\t\t})\n\t\t\t}),\n\t\t\tzIndex: 92,\n\t\t\tstyle: function(feature, resolution) {return style_map_ol3js_1_0[feature.getGeometry().getType()];}\n\t\t  });\n\t\t  map_ol3js_1.addLayer(vectorL0);addControls2Map(map_ol3js_1,0,0,3,0,5,6,7,0,1);\nosm_addPopupClickhandler(map_ol3js_1,  \"map_ol3js_1\"); \nosm_addMouseHover(map_ol3js_1); <\/script>\n","protected":false},"excerpt":{"rendered":"<p>In der Nacht hat es deutlich abgek\u00fchlt, so dass es sich in meinem Schlafraum gut aushalten lie\u00df. Auch der n\u00e4chste Tag ist sch\u00f6n, aber nicht mehr ganz so hei\u00df angesagt. Ich nehme ein Fr\u00fchst\u00fcck im Starbucks im nahe gelegenen Einkaufszentrum. An der K\u00fcste werde ich dann auf einmal von starkem Nebel \u00fcberrascht. Ich komme an [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[58,32,5],"class_list":["post-1741","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-cardiff","tag-kalifornien","tag-usa"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts\/1741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/comments?post=1741"}],"version-history":[{"count":0,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/posts\/1741\/revisions"}],"wp:attachment":[{"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/media?parent=1741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/categories?post=1741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gothein.de\/reiseblog\/wp-json\/wp\/v2\/tags?post=1741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}